{"id":8057,"date":"2025-11-02T14:29:18","date_gmt":"2025-11-02T17:29:18","guid":{"rendered":"https:\/\/radioclanfm.com\/clanespectaculos\/?p=8057"},"modified":"2025-11-02T14:29:18","modified_gmt":"2025-11-02T17:29:18","slug":"que-hizo-paula-robles-la-mama-de-juana-tinelli-en-medio-del-conflicto-con-marcelo-tinelli","status":"publish","type":"post","link":"https:\/\/radioclanfm.com\/clanespectaculos\/que-hizo-paula-robles-la-mama-de-juana-tinelli-en-medio-del-conflicto-con-marcelo-tinelli\/","title":{"rendered":"Qu\u00e9 hizo Paula Robles, la mam\u00e1 de Juana Tinelli, en medio del conflicto con Marcelo Tinelli"},"content":{"rendered":"<p>Su posteo fue luego de que la hija que tuvo con el conductor de TV denunciara amenazas de muerte.<\/p>\n<div class=\"col-content\"><main class=\"col-content\"><\/p>\n<div class=\"default-article-color article__body article__article\">\n<p class=\"paragraph font__body-regular\"><b>Juana Tinelli<\/b>\u00a0denunci\u00f3 que recibi\u00f3\u00a0<b>amenazas de muerte<\/b>. Luego de que se conociera esta noticia, escribi\u00f3 un descargo en el que criticaba ciertas actitudes de su pap\u00e1,\u00a0<b>Marcelo<\/b>.<\/p>\n<div class=\"AV6543bedcd858799fe90b5c47\">\n<div id=\"aniBox\">\n<div id=\"aniplayer_AV6543bedcd858799fe90b5c47-1762104469151\">\n<div id=\"aniplayer_AV6543bedcd858799fe90b5c47-1762104469151gui\">\n<div id=\"av-caption\">\n<div id=\"av-close-btn-overlay\" class=\"av-pos-top-left\"><\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<div id=\"ad-slot-infeed\" class=\"infeed-container ad-slot-infeed ad-slot\" data-adtype=\"infeed\" data-lazyload=\"1\" data-google-query-id=\"CNrQ6s_-05ADFTIl4AMd9VsjKQ\">\n<div id=\"google_ads_iframe_\/113951150\/tn-arc\/nota\/infeed_0__container__\"><\/div>\n<\/div>\n<p class=\"paragraph font__body-regular\">En medio del conflicto,\u00a0<b>Paula Robles<\/b><b>\u00a0<\/b>-la mam\u00e1 de la joven de 22 a\u00f1os- sorprendi\u00f3 en sus redes sociales con una profunda\u00a0<b>reflexi\u00f3n\u00a0<\/b>sobre las decisiones de las personas.<\/p>\n<p class=\"paragraph font__body-regular\">A trav\u00e9s de sus historias de Instagram, la ex de Marcelo Tinelli comparti\u00f3 un video de una charla en la que la australiana<b>\u00a0Merran Poplar\u00a0<\/b>expres\u00f3:\u00a0<b>\u201cEn general queremos cambiar a las otras personas y las cosas que est\u00e1n pasando\u201d<\/b>.<\/p>\n<figure class=\"\" data-testid=\"figure-testid\">\n<div class=\"aspect_ratio__container\"><picture class=\"responsive-image\"><source srcset=\"https:\/\/tn.com.ar\/resizer\/v2\/paula-robles-compartio-una-reflexion-en-sus-redes-sobre-las-decisiones-ajenas-foto-instagrammariapaularobles314-USOEEFYFKNHSBJZ2PRHTX3USJQ.jpg?auth=06ddeb7ec7c2ec1bcd54f45667bc48068468ed2285a5de922157446d8d2ef544&amp;width=767\" type=\"image\/jpg\" media=\"(max-width: 728px)\" \/><source srcset=\"https:\/\/tn.com.ar\/resizer\/v2\/paula-robles-compartio-una-reflexion-en-sus-redes-sobre-las-decisiones-ajenas-foto-instagrammariapaularobles314-USOEEFYFKNHSBJZ2PRHTX3USJQ.jpg?auth=06ddeb7ec7c2ec1bcd54f45667bc48068468ed2285a5de922157446d8d2ef544&amp;width=1023\" type=\"image\/jpg\" media=\"(max-width: 1023px)\" \/><source srcset=\"https:\/\/tn.com.ar\/resizer\/v2\/paula-robles-compartio-una-reflexion-en-sus-redes-sobre-las-decisiones-ajenas-foto-instagrammariapaularobles314-USOEEFYFKNHSBJZ2PRHTX3USJQ.jpg?auth=06ddeb7ec7c2ec1bcd54f45667bc48068468ed2285a5de922157446d8d2ef544&amp;width=1440\" type=\"image\/jpg\" \/><img loading=\"lazy\" decoding=\"async\" class=\"image content-image image_placeholder\" src=\"https:\/\/tn.com.ar\/resizer\/v2\/paula-robles-compartio-una-reflexion-en-sus-redes-sobre-las-decisiones-ajenas-foto-instagrammariapaularobles314-USOEEFYFKNHSBJZ2PRHTX3USJQ.jpg?auth=06ddeb7ec7c2ec1bcd54f45667bc48068468ed2285a5de922157446d8d2ef544&amp;width=767\" alt=\"Paula Robles comparti\u00f3 una reflexi\u00f3n en sus redes sobre las decisiones ajenas. (Foto: Instagram\/mariapaularobles314)\" width=\"767\" height=\"1377\" data-testid=\"loading-testid\" \/><\/picture><\/div><figcaption class=\"caption_image\" data-testid=\"figcaption-testid\">\n<div class=\"image_caption \">Paula Robles comparti\u00f3 una reflexi\u00f3n en sus redes sobre las decisiones ajenas. (Foto: Instagram\/mariapaularobles314)<\/div>\n<\/figcaption><\/figure>\n<p class=\"paragraph font__body-regular\">\u201cHay otro mundo en el que s\u00ed tenemos posibilidades de hacer, tomar decisiones e influir en la situaci\u00f3n. Es muy importante\u00a0<b>tener en claro<\/b>\u00a0cuando hablamos del \u2018uso de uno mismo\u2019,\u00a0<b>qu\u00e9 cae dentro de nuestro \u00e1mbito de influencia<\/b>, qu\u00e9 podemos dirigir y qu\u00e9 no\u201d, se escucha tambi\u00e9n como parte de la reflexi\u00f3n.<\/p>\n<p class=\"paragraph font__body-regular\">\u201cMerran hizo una reflexi\u00f3n sobre aquello que est\u00e1 dentro de nuestro \u00e1mbito de influencia, y<b>\u00a0aquello que no podemos controlar<\/b>\u201d, se describe en la publicaci\u00f3n que Paula subi\u00f3 para sus seguidores.<\/p>\n<p class=\"paragraph font__body-regular\">Siguiendo esta l\u00ednea de pensamiento, cabe destacar que en parte de su descargo, Juanita manifest\u00f3: \u201cNo comparto ni avalo\u00a0<b>muchas de las decisiones que mi pap\u00e1 ha tomado<\/b>\u00a0en los \u00faltimos a\u00f1os. Pero s\u00ed me afectan profundamente.\u00a0<b>No puedo responsabilizarme por lo que no hice<\/b>, pero s\u00ed por lo que siento y por c\u00f3mo eso me atraviesa, a tal punto de temer por mi vida, por mi libertad\u201d.<\/p>\n<p class=\"paragraph font__body-regular\">Y remarc\u00f3: \u201cTengo 22 a\u00f1os, tengo\u00a0<b>mi propia mirada y mi manera de sentir<\/b>. Y, m\u00e1s all\u00e1 de todo lo que mi apellido representa, quiero expresar mi opini\u00f3n sincera, mi verdad y de alguna manera exponer mi l\u00edmite\u201d.<\/p>\n<h2 class=\"font--primary font__display\">La reacci\u00f3n de Marcelo Tinelli al descargo de su hija Juanita<\/h2>\n<p class=\"paragraph font__body-regular\">Despu\u00e9s del comunicado de Juanita, el conductor de TV public\u00f3 una emotiva foto junto a Juanita en la que busc\u00f3 demostrarle el cari\u00f1o que le tiene.\u00a0<b>\u201cTe amo siempre mi pebe, con toda mi alma\u201d<\/b>, escribi\u00f3 el conductor.<\/p>\n<figure class=\"\" data-testid=\"figure-testid\">\n<div class=\"aspect_ratio__container\"><picture class=\"responsive-image\"><source srcset=\"https:\/\/tn.com.ar\/resizer\/v2\/la-historia-que-marcelo-le-dedico-a-su-hija-juana-tinelli-foto-instagrammarcelotinelli-G43K4S6W2BDUZDGNXT6YO76LNI.jpg?auth=0a6ff0f5ccd724f99bd2de9c7d28d4dd5903543471edab0f9824a479e001c777&amp;width=767\" type=\"image\/jpg\" media=\"(max-width: 728px)\" \/><source srcset=\"https:\/\/tn.com.ar\/resizer\/v2\/la-historia-que-marcelo-le-dedico-a-su-hija-juana-tinelli-foto-instagrammarcelotinelli-G43K4S6W2BDUZDGNXT6YO76LNI.jpg?auth=0a6ff0f5ccd724f99bd2de9c7d28d4dd5903543471edab0f9824a479e001c777&amp;width=1023\" type=\"image\/jpg\" media=\"(max-width: 1023px)\" \/><source srcset=\"https:\/\/tn.com.ar\/resizer\/v2\/la-historia-que-marcelo-le-dedico-a-su-hija-juana-tinelli-foto-instagrammarcelotinelli-G43K4S6W2BDUZDGNXT6YO76LNI.jpg?auth=0a6ff0f5ccd724f99bd2de9c7d28d4dd5903543471edab0f9824a479e001c777&amp;width=1440\" type=\"image\/jpg\" \/><img loading=\"lazy\" decoding=\"async\" class=\"image content-image image_placeholder\" src=\"https:\/\/tn.com.ar\/resizer\/v2\/la-historia-que-marcelo-le-dedico-a-su-hija-juana-tinelli-foto-instagrammarcelotinelli-G43K4S6W2BDUZDGNXT6YO76LNI.jpg?auth=0a6ff0f5ccd724f99bd2de9c7d28d4dd5903543471edab0f9824a479e001c777&amp;width=767\" alt=\"La historia que Marcelo le dedic\u00f3 a su hija Juana Tinelli. (Foto: Instagram\/marcelotinelli)\" width=\"767\" height=\"1376\" data-testid=\"loading-testid\" \/><\/picture><\/div><figcaption class=\"caption_image\" data-testid=\"figcaption-testid\">\n<div class=\"image_caption \">La historia que Marcelo le dedic\u00f3 a su hija Juana Tinelli. (Foto: Instagram\/marcelotinelli)<\/div>\n<\/figcaption><\/figure>\n<p class=\"paragraph font__body-regular\">Antes de este mensaje que le dedic\u00f3 a la joven, Marcelo hab\u00eda subido otra historia en la que dio su versi\u00f3n del drama que atraviesan, y que tambi\u00e9n fue\u00a0<b>replicada por Candelaria Tinelli<\/b>. \u201cHabr\u00e1n podido ver que mi hija Juani tuvo una experiencia muy dolorosa para ella y para todos nosotros,\u00a0<b>con esta amenaza que recibimos<\/b>\u201d, expres\u00f3 \u00e9l.<\/p>\n<figure class=\"\" data-testid=\"figure-testid\">\n<div class=\"aspect_ratio__container\"><picture class=\"responsive-image\"><source srcset=\"https:\/\/tn.com.ar\/resizer\/v2\/tanto-marcelo-como-candelaria-tinelli-compartieron-el-mismo-mensaje-en-sus-redes-foto-instagramcandelariatinelli-HGIT4ETGLRGHVEDZFT4TULQCJ4.jpg?auth=58d14f2e51e724c8c219deb33d1f9970b49bc6c75509505031f1826555146fa0&amp;width=767\" type=\"image\/jpg\" media=\"(max-width: 728px)\" \/><source srcset=\"https:\/\/tn.com.ar\/resizer\/v2\/tanto-marcelo-como-candelaria-tinelli-compartieron-el-mismo-mensaje-en-sus-redes-foto-instagramcandelariatinelli-HGIT4ETGLRGHVEDZFT4TULQCJ4.jpg?auth=58d14f2e51e724c8c219deb33d1f9970b49bc6c75509505031f1826555146fa0&amp;width=1023\" type=\"image\/jpg\" media=\"(max-width: 1023px)\" \/><source srcset=\"https:\/\/tn.com.ar\/resizer\/v2\/tanto-marcelo-como-candelaria-tinelli-compartieron-el-mismo-mensaje-en-sus-redes-foto-instagramcandelariatinelli-HGIT4ETGLRGHVEDZFT4TULQCJ4.jpg?auth=58d14f2e51e724c8c219deb33d1f9970b49bc6c75509505031f1826555146fa0&amp;width=1440\" type=\"image\/jpg\" \/><img loading=\"lazy\" decoding=\"async\" class=\"image content-image image_placeholder\" src=\"https:\/\/tn.com.ar\/resizer\/v2\/tanto-marcelo-como-candelaria-tinelli-compartieron-el-mismo-mensaje-en-sus-redes-foto-instagramcandelariatinelli-HGIT4ETGLRGHVEDZFT4TULQCJ4.jpg?auth=58d14f2e51e724c8c219deb33d1f9970b49bc6c75509505031f1826555146fa0&amp;width=767\" alt=\"Tanto Marcelo como Candelaria Tinelli compartieron el mismo mensaje en sus redes. (Foto: Instagram\/candelariatinelli)\" width=\"767\" height=\"1342\" data-testid=\"loading-testid\" \/><\/picture><\/div><figcaption class=\"caption_image\" data-testid=\"figcaption-testid\">\n<div class=\"image_caption \">Tanto Marcelo como Candelaria Tinelli compartieron el mismo mensaje en sus redes. (Foto: Instagram\/candelariatinelli)<\/div>\n<\/figcaption><\/figure>\n<p class=\"paragraph font__body-regular\">\u201c<b>Estamos muy tristes y preocupados por lo que pas\u00f3<\/b>, y ocup\u00e1ndome para llegar hasta el fondo de la investigaci\u00f3n y dar con los verdaderos responsables\u201d, dijo el conductor.<\/p>\n<p class=\"paragraph font__body-regular\">Y destac\u00f3: \u201c<b>Les pido por favor que respeten mi reserva<\/b>, ya que en este tema no voy a hacer declaraciones, y cualquier cosa que ustedes tengan que saber, se los voy a comunicar. Muchas gracias\u201d.<\/p>\n<\/div>\n<p><\/main><\/div>\n<aside class=\"col-right-rail right-rail\">\n<div id=\"parent-ad-slot-caja\" class=\"ad-container caja_ad \">\n<div class=\"ad-content\">\n<div id=\"ad-slot-caja\" class=\"ad-slot-caja ad-slot\" data-adtype=\"caja\" data-lazyload=\"1\" data-google-query-id=\"CN7J6c_-05ADFaFV3QIdQ0AmIw\"><\/div>\n<\/div>\n<\/div>\n<\/aside>\n","protected":false},"excerpt":{"rendered":"<p>Su posteo fue luego de que la hija que tuvo con el conductor de TV denunciara amenazas de muerte. Juana Tinelli\u00a0denunci\u00f3 que recibi\u00f3\u00a0amenazas de muerte. Luego de que se conociera esta noticia, escribi\u00f3 un descargo en el que criticaba ciertas actitudes de su pap\u00e1,\u00a0Marcelo. En medio del conflicto,\u00a0Paula Robles\u00a0-la mam\u00e1 de la joven de 22 [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":8060,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"rop_custom_images_group":[],"rop_custom_messages_group":[],"rop_publish_now":"initial","rop_publish_now_accounts":[],"rop_publish_now_history":[],"rop_publish_now_status":"pending","footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","enabled":false},"version":2}},"categories":[12],"tags":[],"class_list":["post-8057","post","type-post","status-publish","format-standard","has-post-thumbnail","category-espectaculos"],"jetpack_publicize_connections":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.2 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Qu\u00e9 hizo Paula Robles, la mam\u00e1 de Juana Tinelli, en medio del conflicto con Marcelo Tinelli - CLAN ESPECTACULOS<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/radioclanfm.com\/clanespectaculos\/que-hizo-paula-robles-la-mama-de-juana-tinelli-en-medio-del-conflicto-con-marcelo-tinelli\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Qu\u00e9 hizo Paula Robles, la mam\u00e1 de Juana Tinelli, en medio del conflicto con Marcelo Tinelli - CLAN ESPECTACULOS\" \/>\n<meta property=\"og:description\" content=\"Su posteo fue luego de que la hija que tuvo con el conductor de TV denunciara amenazas de muerte. Juana Tinelli\u00a0denunci\u00f3 que recibi\u00f3\u00a0amenazas de muerte. Luego de que se conociera esta noticia, escribi\u00f3 un descargo en el que criticaba ciertas actitudes de su pap\u00e1,\u00a0Marcelo. En medio del conflicto,\u00a0Paula Robles\u00a0-la mam\u00e1 de la joven de 22 [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/radioclanfm.com\/clanespectaculos\/que-hizo-paula-robles-la-mama-de-juana-tinelli-en-medio-del-conflicto-con-marcelo-tinelli\/\" \/>\n<meta property=\"og:site_name\" content=\"CLAN ESPECTACULOS\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/clanespectaculos\/\" \/>\n<meta property=\"article:published_time\" content=\"2025-11-02T17:29:18+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/radioclanfm.com\/clanespectaculos\/wp-content\/uploads\/sites\/2\/2025\/11\/UIs_NTtW.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"900\" \/>\n\t<meta property=\"og:image:height\" content=\"504\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"E-GRUPOCLAN\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@clanespectok\" \/>\n<meta name=\"twitter:site\" content=\"@clanespectok\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"E-GRUPOCLAN\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/radioclanfm.com\\\/clanespectaculos\\\/que-hizo-paula-robles-la-mama-de-juana-tinelli-en-medio-del-conflicto-con-marcelo-tinelli\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/radioclanfm.com\\\/clanespectaculos\\\/que-hizo-paula-robles-la-mama-de-juana-tinelli-en-medio-del-conflicto-con-marcelo-tinelli\\\/\"},\"author\":{\"name\":\"E-GRUPOCLAN\",\"@id\":\"https:\\\/\\\/radioclanfm.com\\\/clanespectaculos\\\/#\\\/schema\\\/person\\\/9734813083303230f3ad84d99171b20c\"},\"headline\":\"Qu\u00e9 hizo Paula Robles, la mam\u00e1 de Juana Tinelli, en medio del conflicto con Marcelo Tinelli\",\"datePublished\":\"2025-11-02T17:29:18+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/radioclanfm.com\\\/clanespectaculos\\\/que-hizo-paula-robles-la-mama-de-juana-tinelli-en-medio-del-conflicto-con-marcelo-tinelli\\\/\"},\"wordCount\":560,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/radioclanfm.com\\\/clanespectaculos\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/radioclanfm.com\\\/clanespectaculos\\\/que-hizo-paula-robles-la-mama-de-juana-tinelli-en-medio-del-conflicto-con-marcelo-tinelli\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/radioclanfm.com\\\/clanespectaculos\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2025\\\/11\\\/UIs_NTtW.jpg\",\"articleSection\":[\"Espectaculos\"],\"inLanguage\":\"es-AR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/radioclanfm.com\\\/clanespectaculos\\\/que-hizo-paula-robles-la-mama-de-juana-tinelli-en-medio-del-conflicto-con-marcelo-tinelli\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/radioclanfm.com\\\/clanespectaculos\\\/que-hizo-paula-robles-la-mama-de-juana-tinelli-en-medio-del-conflicto-con-marcelo-tinelli\\\/\",\"url\":\"https:\\\/\\\/radioclanfm.com\\\/clanespectaculos\\\/que-hizo-paula-robles-la-mama-de-juana-tinelli-en-medio-del-conflicto-con-marcelo-tinelli\\\/\",\"name\":\"Qu\u00e9 hizo Paula Robles, la mam\u00e1 de Juana Tinelli, en medio del conflicto con Marcelo Tinelli - CLAN ESPECTACULOS\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/radioclanfm.com\\\/clanespectaculos\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/radioclanfm.com\\\/clanespectaculos\\\/que-hizo-paula-robles-la-mama-de-juana-tinelli-en-medio-del-conflicto-con-marcelo-tinelli\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/radioclanfm.com\\\/clanespectaculos\\\/que-hizo-paula-robles-la-mama-de-juana-tinelli-en-medio-del-conflicto-con-marcelo-tinelli\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/radioclanfm.com\\\/clanespectaculos\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2025\\\/11\\\/UIs_NTtW.jpg\",\"datePublished\":\"2025-11-02T17:29:18+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/radioclanfm.com\\\/clanespectaculos\\\/que-hizo-paula-robles-la-mama-de-juana-tinelli-en-medio-del-conflicto-con-marcelo-tinelli\\\/#breadcrumb\"},\"inLanguage\":\"es-AR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/radioclanfm.com\\\/clanespectaculos\\\/que-hizo-paula-robles-la-mama-de-juana-tinelli-en-medio-del-conflicto-con-marcelo-tinelli\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es-AR\",\"@id\":\"https:\\\/\\\/radioclanfm.com\\\/clanespectaculos\\\/que-hizo-paula-robles-la-mama-de-juana-tinelli-en-medio-del-conflicto-con-marcelo-tinelli\\\/#primaryimage\",\"url\":\"https:\\\/\\\/radioclanfm.com\\\/clanespectaculos\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2025\\\/11\\\/UIs_NTtW.jpg\",\"contentUrl\":\"https:\\\/\\\/radioclanfm.com\\\/clanespectaculos\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2025\\\/11\\\/UIs_NTtW.jpg\",\"width\":900,\"height\":504},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/radioclanfm.com\\\/clanespectaculos\\\/que-hizo-paula-robles-la-mama-de-juana-tinelli-en-medio-del-conflicto-con-marcelo-tinelli\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inicio\",\"item\":\"https:\\\/\\\/radioclanfm.com\\\/clanespectaculos\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Qu\u00e9 hizo Paula Robles, la mam\u00e1 de Juana Tinelli, en medio del conflicto con Marcelo Tinelli\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/radioclanfm.com\\\/clanespectaculos\\\/#website\",\"url\":\"https:\\\/\\\/radioclanfm.com\\\/clanespectaculos\\\/\",\"name\":\"CLAN ESPECTACULOS\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/radioclanfm.com\\\/clanespectaculos\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/radioclanfm.com\\\/clanespectaculos\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es-AR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/radioclanfm.com\\\/clanespectaculos\\\/#organization\",\"name\":\"CLAN ESPECTACULOS\",\"url\":\"https:\\\/\\\/radioclanfm.com\\\/clanespectaculos\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es-AR\",\"@id\":\"https:\\\/\\\/radioclanfm.com\\\/clanespectaculos\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/radioclanfm.com\\\/clanespectaculos\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2026\\\/04\\\/ChatGPT-Image-23-mar-2026-10_09_00.png\",\"contentUrl\":\"https:\\\/\\\/radioclanfm.com\\\/clanespectaculos\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2026\\\/04\\\/ChatGPT-Image-23-mar-2026-10_09_00.png\",\"width\":1024,\"height\":1024,\"caption\":\"CLAN ESPECTACULOS\"},\"image\":{\"@id\":\"https:\\\/\\\/radioclanfm.com\\\/clanespectaculos\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/clanespectaculos\\\/\",\"https:\\\/\\\/x.com\\\/clanespectok\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/radioclanfm.com\\\/clanespectaculos\\\/#\\\/schema\\\/person\\\/9734813083303230f3ad84d99171b20c\",\"name\":\"E-GRUPOCLAN\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es-AR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/af6e19837c3d6a212034a48c7b3818d2ac1826f6025df0155da5a186ad321d79?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/af6e19837c3d6a212034a48c7b3818d2ac1826f6025df0155da5a186ad321d79?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/af6e19837c3d6a212034a48c7b3818d2ac1826f6025df0155da5a186ad321d79?s=96&d=mm&r=g\",\"caption\":\"E-GRUPOCLAN\"},\"sameAs\":[\"https:\\\/\\\/radioclanfm.com\"],\"url\":\"https:\\\/\\\/radioclanfm.com\\\/clanespectaculos\\\/author\\\/admin\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Qu\u00e9 hizo Paula Robles, la mam\u00e1 de Juana Tinelli, en medio del conflicto con Marcelo Tinelli - CLAN ESPECTACULOS","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/radioclanfm.com\/clanespectaculos\/que-hizo-paula-robles-la-mama-de-juana-tinelli-en-medio-del-conflicto-con-marcelo-tinelli\/","og_locale":"es_ES","og_type":"article","og_title":"Qu\u00e9 hizo Paula Robles, la mam\u00e1 de Juana Tinelli, en medio del conflicto con Marcelo Tinelli - CLAN ESPECTACULOS","og_description":"Su posteo fue luego de que la hija que tuvo con el conductor de TV denunciara amenazas de muerte. Juana Tinelli\u00a0denunci\u00f3 que recibi\u00f3\u00a0amenazas de muerte. Luego de que se conociera esta noticia, escribi\u00f3 un descargo en el que criticaba ciertas actitudes de su pap\u00e1,\u00a0Marcelo. En medio del conflicto,\u00a0Paula Robles\u00a0-la mam\u00e1 de la joven de 22 [&hellip;]","og_url":"https:\/\/radioclanfm.com\/clanespectaculos\/que-hizo-paula-robles-la-mama-de-juana-tinelli-en-medio-del-conflicto-con-marcelo-tinelli\/","og_site_name":"CLAN ESPECTACULOS","article_publisher":"https:\/\/www.facebook.com\/clanespectaculos\/","article_published_time":"2025-11-02T17:29:18+00:00","og_image":[{"width":900,"height":504,"url":"https:\/\/radioclanfm.com\/clanespectaculos\/wp-content\/uploads\/sites\/2\/2025\/11\/UIs_NTtW.jpg","type":"image\/jpeg"}],"author":"E-GRUPOCLAN","twitter_card":"summary_large_image","twitter_creator":"@clanespectok","twitter_site":"@clanespectok","twitter_misc":{"Escrito por":"E-GRUPOCLAN","Tiempo de lectura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/radioclanfm.com\/clanespectaculos\/que-hizo-paula-robles-la-mama-de-juana-tinelli-en-medio-del-conflicto-con-marcelo-tinelli\/#article","isPartOf":{"@id":"https:\/\/radioclanfm.com\/clanespectaculos\/que-hizo-paula-robles-la-mama-de-juana-tinelli-en-medio-del-conflicto-con-marcelo-tinelli\/"},"author":{"name":"E-GRUPOCLAN","@id":"https:\/\/radioclanfm.com\/clanespectaculos\/#\/schema\/person\/9734813083303230f3ad84d99171b20c"},"headline":"Qu\u00e9 hizo Paula Robles, la mam\u00e1 de Juana Tinelli, en medio del conflicto con Marcelo Tinelli","datePublished":"2025-11-02T17:29:18+00:00","mainEntityOfPage":{"@id":"https:\/\/radioclanfm.com\/clanespectaculos\/que-hizo-paula-robles-la-mama-de-juana-tinelli-en-medio-del-conflicto-con-marcelo-tinelli\/"},"wordCount":560,"commentCount":0,"publisher":{"@id":"https:\/\/radioclanfm.com\/clanespectaculos\/#organization"},"image":{"@id":"https:\/\/radioclanfm.com\/clanespectaculos\/que-hizo-paula-robles-la-mama-de-juana-tinelli-en-medio-del-conflicto-con-marcelo-tinelli\/#primaryimage"},"thumbnailUrl":"https:\/\/radioclanfm.com\/clanespectaculos\/wp-content\/uploads\/sites\/2\/2025\/11\/UIs_NTtW.jpg","articleSection":["Espectaculos"],"inLanguage":"es-AR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/radioclanfm.com\/clanespectaculos\/que-hizo-paula-robles-la-mama-de-juana-tinelli-en-medio-del-conflicto-con-marcelo-tinelli\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/radioclanfm.com\/clanespectaculos\/que-hizo-paula-robles-la-mama-de-juana-tinelli-en-medio-del-conflicto-con-marcelo-tinelli\/","url":"https:\/\/radioclanfm.com\/clanespectaculos\/que-hizo-paula-robles-la-mama-de-juana-tinelli-en-medio-del-conflicto-con-marcelo-tinelli\/","name":"Qu\u00e9 hizo Paula Robles, la mam\u00e1 de Juana Tinelli, en medio del conflicto con Marcelo Tinelli - CLAN ESPECTACULOS","isPartOf":{"@id":"https:\/\/radioclanfm.com\/clanespectaculos\/#website"},"primaryImageOfPage":{"@id":"https:\/\/radioclanfm.com\/clanespectaculos\/que-hizo-paula-robles-la-mama-de-juana-tinelli-en-medio-del-conflicto-con-marcelo-tinelli\/#primaryimage"},"image":{"@id":"https:\/\/radioclanfm.com\/clanespectaculos\/que-hizo-paula-robles-la-mama-de-juana-tinelli-en-medio-del-conflicto-con-marcelo-tinelli\/#primaryimage"},"thumbnailUrl":"https:\/\/radioclanfm.com\/clanespectaculos\/wp-content\/uploads\/sites\/2\/2025\/11\/UIs_NTtW.jpg","datePublished":"2025-11-02T17:29:18+00:00","breadcrumb":{"@id":"https:\/\/radioclanfm.com\/clanespectaculos\/que-hizo-paula-robles-la-mama-de-juana-tinelli-en-medio-del-conflicto-con-marcelo-tinelli\/#breadcrumb"},"inLanguage":"es-AR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/radioclanfm.com\/clanespectaculos\/que-hizo-paula-robles-la-mama-de-juana-tinelli-en-medio-del-conflicto-con-marcelo-tinelli\/"]}]},{"@type":"ImageObject","inLanguage":"es-AR","@id":"https:\/\/radioclanfm.com\/clanespectaculos\/que-hizo-paula-robles-la-mama-de-juana-tinelli-en-medio-del-conflicto-con-marcelo-tinelli\/#primaryimage","url":"https:\/\/radioclanfm.com\/clanespectaculos\/wp-content\/uploads\/sites\/2\/2025\/11\/UIs_NTtW.jpg","contentUrl":"https:\/\/radioclanfm.com\/clanespectaculos\/wp-content\/uploads\/sites\/2\/2025\/11\/UIs_NTtW.jpg","width":900,"height":504},{"@type":"BreadcrumbList","@id":"https:\/\/radioclanfm.com\/clanespectaculos\/que-hizo-paula-robles-la-mama-de-juana-tinelli-en-medio-del-conflicto-con-marcelo-tinelli\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inicio","item":"https:\/\/radioclanfm.com\/clanespectaculos\/"},{"@type":"ListItem","position":2,"name":"Qu\u00e9 hizo Paula Robles, la mam\u00e1 de Juana Tinelli, en medio del conflicto con Marcelo Tinelli"}]},{"@type":"WebSite","@id":"https:\/\/radioclanfm.com\/clanespectaculos\/#website","url":"https:\/\/radioclanfm.com\/clanespectaculos\/","name":"CLAN ESPECTACULOS","description":"","publisher":{"@id":"https:\/\/radioclanfm.com\/clanespectaculos\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/radioclanfm.com\/clanespectaculos\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es-AR"},{"@type":"Organization","@id":"https:\/\/radioclanfm.com\/clanespectaculos\/#organization","name":"CLAN ESPECTACULOS","url":"https:\/\/radioclanfm.com\/clanespectaculos\/","logo":{"@type":"ImageObject","inLanguage":"es-AR","@id":"https:\/\/radioclanfm.com\/clanespectaculos\/#\/schema\/logo\/image\/","url":"https:\/\/radioclanfm.com\/clanespectaculos\/wp-content\/uploads\/sites\/2\/2026\/04\/ChatGPT-Image-23-mar-2026-10_09_00.png","contentUrl":"https:\/\/radioclanfm.com\/clanespectaculos\/wp-content\/uploads\/sites\/2\/2026\/04\/ChatGPT-Image-23-mar-2026-10_09_00.png","width":1024,"height":1024,"caption":"CLAN ESPECTACULOS"},"image":{"@id":"https:\/\/radioclanfm.com\/clanespectaculos\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/clanespectaculos\/","https:\/\/x.com\/clanespectok"]},{"@type":"Person","@id":"https:\/\/radioclanfm.com\/clanespectaculos\/#\/schema\/person\/9734813083303230f3ad84d99171b20c","name":"E-GRUPOCLAN","image":{"@type":"ImageObject","inLanguage":"es-AR","@id":"https:\/\/secure.gravatar.com\/avatar\/af6e19837c3d6a212034a48c7b3818d2ac1826f6025df0155da5a186ad321d79?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/af6e19837c3d6a212034a48c7b3818d2ac1826f6025df0155da5a186ad321d79?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/af6e19837c3d6a212034a48c7b3818d2ac1826f6025df0155da5a186ad321d79?s=96&d=mm&r=g","caption":"E-GRUPOCLAN"},"sameAs":["https:\/\/radioclanfm.com"],"url":"https:\/\/radioclanfm.com\/clanespectaculos\/author\/admin\/"}]}},"_links":{"self":[{"href":"https:\/\/radioclanfm.com\/clanespectaculos\/wp-json\/wp\/v2\/posts\/8057","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/radioclanfm.com\/clanespectaculos\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/radioclanfm.com\/clanespectaculos\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/radioclanfm.com\/clanespectaculos\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/radioclanfm.com\/clanespectaculos\/wp-json\/wp\/v2\/comments?post=8057"}],"version-history":[{"count":1,"href":"https:\/\/radioclanfm.com\/clanespectaculos\/wp-json\/wp\/v2\/posts\/8057\/revisions"}],"predecessor-version":[{"id":8061,"href":"https:\/\/radioclanfm.com\/clanespectaculos\/wp-json\/wp\/v2\/posts\/8057\/revisions\/8061"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/radioclanfm.com\/clanespectaculos\/wp-json\/wp\/v2\/media\/8060"}],"wp:attachment":[{"href":"https:\/\/radioclanfm.com\/clanespectaculos\/wp-json\/wp\/v2\/media?parent=8057"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/radioclanfm.com\/clanespectaculos\/wp-json\/wp\/v2\/categories?post=8057"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/radioclanfm.com\/clanespectaculos\/wp-json\/wp\/v2\/tags?post=8057"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}