{"id":16406,"date":"2026-05-12T13:28:04","date_gmt":"2026-05-12T16:28:04","guid":{"rendered":"https:\/\/radioclanfm.com\/clanespectaculos\/?p=16406"},"modified":"2026-05-12T13:28:04","modified_gmt":"2026-05-12T16:28:04","slug":"un-grosero-error-en-los-porcentajes-de-eliminacion-expuso-a-gran-hermano-2026-y-causo-polemica-en-las-redes","status":"publish","type":"post","link":"https:\/\/radioclanfm.com\/clanespectaculos\/un-grosero-error-en-los-porcentajes-de-eliminacion-expuso-a-gran-hermano-2026-y-causo-polemica-en-las-redes\/","title":{"rendered":"Un grosero error en los porcentajes de eliminaci\u00f3n expuso a \u201cGran Hermano 2026\u201d y caus\u00f3 pol\u00e9mica en las redes"},"content":{"rendered":"<p>Fue cuando Santiago del Moro daba los n\u00fameros parciales del versus entre Dani De Luc\u00eda y Danelik.<\/p>\n<div class=\"col-content\"><main class=\"col-content\"><\/p>\n<div class=\"default-article-color article__body article__article\">\n<p class=\"paragraph font__body-regular\">La noche de\u00a0<i><b>Gran Hermano: Generaci\u00f3n Dorada<\/b><\/i>\u00a0(<i>Telefe<\/i>) fue tensa por el versus al que se hab\u00eda llegado en el final de la votaci\u00f3n. De un lado,\u00a0<b>Daniela De Luc\u00eda<\/b>\u00a0y del otro,\u00a0<b>Danelik<\/b>, ambas de grupos enfrentados. La paridad, finalmente, tuvo a una eliminada y la \u201ccoach\u201d de la casa se tuvo que ir.<\/p>\n<div class=\"teads-adCall\"><\/div>\n<div id=\"ad-slot-infeed\" class=\"infeed-container ad-slot-infeed ad-slot\" data-adtype=\"infeed\" data-lazyload=\"1\" data-google-query-id=\"CIvSjLaVtJQDFRVLuAQdgn4jCQ\">\n<div id=\"google_ads_iframe_\/113951150\/tn-arc\/nota\/infeed_0__container__\"><iframe id=\"google_ads_iframe_\/113951150\/tn-arc\/nota\/infeed_0\" tabindex=\"0\" title=\"Contenido de anuncios de terceros\" name=\"google_ads_iframe_\/113951150\/tn-arc\/nota\/infeed_0\" width=\"1\" height=\"1\" frameborder=\"0\" marginwidth=\"0\" marginheight=\"0\" scrolling=\"no\" aria-label=\"Anuncio\" data-google-container-id=\"9\" data-load-complete=\"true\" data-mce-fragment=\"1\"><\/iframe><\/div>\n<\/div>\n<p class=\"paragraph font__body-regular\">Sin embargo, en las redes, empez\u00f3 a resonar una palabra que siempre, en estas instancias, sobrevuela: fraude. Muchas cuentas replicaron sin parar un porcentaje que a simple vista<b>\u00a0se nota que es un error.<\/b><\/p>\n<div class=\"story-list\" data-mrf-recirculation=\"IL_fPSS4oUaSUaKNHLf4mpe3g\" data-mrf-root-experiment=\"0952317d-c9e3-4d65-9dd7-85816683fa43\" data-testid=\"text-html\" data-mrf-experience=\"IL_fPSS4oUaSUaKNHLf4mpe3g\">\n<article class=\"card__container card__horizontal\">\n<div class=\"card__body\">\n<header>\n<h3 class=\"card__headline font__display\"><\/h3>\n<\/header>\n<\/div>\n<\/article>\n<\/div>\n<div class=\"marfeel-readmore-slot\" data-mrf-recirculation=\"IL_RNrGCM52Q_ui4aMax3fibg\" data-mrf-root-experiment=\"0952317d-c9e3-4d65-9dd7-85816683fa43\"><\/div>\n<p class=\"paragraph font__body-regular\">Cuando\u00a0<b>Santiago del Moro<\/b>\u00a0estaba cerca de mencionar qui\u00e9n de las dos participantes se iba a ir de la casa, pidi\u00f3 que mostraran los porcentajes que ten\u00edan hasta ese momento.<\/p>\n<p class=\"paragraph font__body-regular\">Una placa evidenci\u00f3 el desliz que hubo:\u00a0<b>53,1 % a 56,9 %,<\/b>\u00a0un n\u00famero que en su totalidad da 110, mayor al 100 que deber\u00eda ser. En el estudio se escuch\u00f3 un murmullo, en ese momento, pero\u00a0<b>el conductor mand\u00f3 un informe.<\/b><\/p>\n<figure class=\"\" data-testid=\"figure-testid\">\n<div class=\"aspect_ratio__container\"><picture class=\"responsive-image\"><source srcset=\"https:\/\/tn.com.ar\/resizer\/v2\/el-error-que-expuso-a-gran-hermano-2026-foto-captura-de-telefe-3SRSACPCYRBE7F4HQXGMH7WGGE.jfif?auth=5de5f357a4f8392a4ad98a5ccc5838606005994b8d7cd730aa259eec989ada95&amp;width=767\" type=\"image\/jpg\" media=\"(max-width: 728px)\" \/><source srcset=\"https:\/\/tn.com.ar\/resizer\/v2\/el-error-que-expuso-a-gran-hermano-2026-foto-captura-de-telefe-3SRSACPCYRBE7F4HQXGMH7WGGE.jfif?auth=5de5f357a4f8392a4ad98a5ccc5838606005994b8d7cd730aa259eec989ada95&amp;width=1023\" type=\"image\/jpg\" media=\"(max-width: 1023px)\" \/><source srcset=\"https:\/\/tn.com.ar\/resizer\/v2\/el-error-que-expuso-a-gran-hermano-2026-foto-captura-de-telefe-3SRSACPCYRBE7F4HQXGMH7WGGE.jfif?auth=5de5f357a4f8392a4ad98a5ccc5838606005994b8d7cd730aa259eec989ada95&amp;width=1440\" type=\"image\/jpg\" \/><img loading=\"lazy\" decoding=\"async\" class=\"image content-image image_placeholder\" src=\"https:\/\/tn.com.ar\/resizer\/v2\/el-error-que-expuso-a-gran-hermano-2026-foto-captura-de-telefe-3SRSACPCYRBE7F4HQXGMH7WGGE.jfif?auth=5de5f357a4f8392a4ad98a5ccc5838606005994b8d7cd730aa259eec989ada95&amp;width=767\" alt=\"El error que expuso a &quot;Gran Hermano 2026&quot;. (Foto: captura de Telefe)\" width=\"767\" height=\"392\" data-testid=\"loading-testid\" \/><\/picture><\/div><figcaption class=\"caption_image\" data-testid=\"figcaption-testid\">\n<div class=\"image_caption \">El error que expuso a &#8220;Gran Hermano 2026&#8221;. (Foto: captura de Telefe)<\/div>\n<\/figcaption><\/figure>\n<p class=\"paragraph font__body-regular\">Cuando el presentador volvi\u00f3 al aire, explic\u00f3 lo que pas\u00f3. \u201c<b>Me dicen reci\u00e9n que hubo un error de tipeo cuando la escribana pas\u00f3 los parciales reci\u00e9n<\/b>\u201d, sostuvo. En la pantalla se ve\u00eda el porcentaje parcial:\u00a0<b>52,9 a 47,1<\/b>.<\/p>\n<p class=\"paragraph font__body-regular\">Del Moro not\u00f3 que desde las tribunas se quejaron y le gritaron. El conductor, enojado, les hizo un reproche. \u201cChicos,\u00a0<b>si no saben cu\u00e1l es cu\u00e1l\u201d<\/b>, sostuvo, en referencia a las sombras que estaban puestas en lugar de las caras de las participantes que defin\u00edan el versus.<\/p>\n<p class=\"paragraph font__body-regular\">En las redes, inmediatamente, se llen\u00f3 de mensajes en contra. Uno de los que impuls\u00f3 el tema, como lo hace habitualmente, fue\u00a0<b>\u00c1ngel de Brito<\/b>, que replic\u00f3 los dos clips que se viralizaron.\u00a0<b>\u201cNervios\u201d, escribi\u00f3 el periodista.<\/b><\/p>\n<p class=\"paragraph font__body-regular\">Varios usuarios no tuvieron piedad con lo que ocurri\u00f3 al aire.\u00a0<b>\u201cAl final Furia ten\u00eda raz\u00f3n\u201d<\/b>; \u201cLa mentira que construyeron se empieza a caer\u201d; \u201cFraude total\u201d; \u201cEs un papel\u00f3n\u201d; \u201cTodo arreglado\u201d; fueron algunos de los mensajes.<\/p>\n<h2 class=\"font--primary font__display\">C\u00f3mo fue la salida de Dani de \u201cGran Hermano 2026\u2033<\/h2>\n<p class=\"paragraph font__body-regular\">Despu\u00e9s de una gala muy intensa en\u00a0<i><b>Gran Hermano: Generaci\u00f3n Dorada\u00a0<\/b><\/i><i>(Telefe)<\/i>,\u00a0<b>Dani de Luc\u00eda<\/b>\u00a0se convirti\u00f3 en la nueva eliminada despu\u00e9s de enfrentarse en el voto negativo y secreto con\u00a0<b>Danelik<\/b>.<\/p>\n<div class=\"genoa_video raw relative\">\n<div class=\"video_placeholder\">\n<div class=\"aspect_ratio__container\"><picture class=\"responsive-image\"><source srcset=\"https:\/\/tn.com.ar\/resizer\/v2\/https%3A%2F%2Fthumbs.vodgc.net%2F1-14-xuJykz1778553352777-1778553496.jpg?auth=e63c651b10ae0874ce0d46fe586e59d16d3cdcabe2f35eab6747bba6788bf6f7&amp;width=767\" type=\"image\/jpg\" media=\"(max-width: 728px)\" \/><source srcset=\"https:\/\/tn.com.ar\/resizer\/v2\/https%3A%2F%2Fthumbs.vodgc.net%2F1-14-xuJykz1778553352777-1778553496.jpg?auth=e63c651b10ae0874ce0d46fe586e59d16d3cdcabe2f35eab6747bba6788bf6f7&amp;width=1023\" type=\"image\/jpg\" media=\"(max-width: 1023px)\" \/><source srcset=\"https:\/\/tn.com.ar\/resizer\/v2\/https%3A%2F%2Fthumbs.vodgc.net%2F1-14-xuJykz1778553352777-1778553496.jpg?auth=e63c651b10ae0874ce0d46fe586e59d16d3cdcabe2f35eab6747bba6788bf6f7&amp;width=1440\" type=\"image\/jpg\" \/><\/picture><\/div>\n<p><button type=\"button\" data-testid=\"video-placeholder-button\"><\/button><\/div>\n<\/div>\n<div class=\"genoa_description font__body-regular\"><\/div>\n<p class=\"paragraph font__body-regular\">A diferencia de otras placas, esta vez los participantes no sab\u00edan qui\u00e9n era el que estaba nominado ni c\u00f3mo se conform\u00f3 la placa. Por eso,\u00a0<b>fueron bajando de a poco<\/b>\u00a0desde el d\u00eda que fueron las nominaciones.<\/p>\n<p class=\"paragraph font__body-regular\"><b>La primera participante en salir de un peligro real fue Cinzia Francischiello<\/b>, que obtuvo apenas el 4,8 % de los votos para abandonar el reality. Antes de volver con sus compa\u00f1eros, lanz\u00f3 una frase que no pas\u00f3 desapercibida: \u201cTengan cuidado los caciques\u201d, en referencia al conflicto que mantiene con Emanuel Di Gioia.<\/p>\n<p class=\"paragraph font__body-regular\">Luego,\u00a0<b>Ema\u00a0<\/b>fue otro de los salvados y m\u00e1s tarde,\u00a0<b>Franco Zunino<\/b>\u00a0qued\u00f3 fuera de la placa. De esta forma, el versus qued\u00f3 entre\u00a0<b>Dani\u00a0<\/b>y\u00a0<b>Danelik<\/b>. La coach motivacional, finalmente, fue la eliminada con\u00a0<b>el 52,7 % de los votos.<\/b><\/p>\n<\/div>\n<p><\/main><\/div>\n<aside class=\"col-right-rail right-rail\">\n<div id=\"parent-ad-slot-caja\" class=\"ad-container caja_ad \">\n<div class=\"ad-content\"><\/div>\n<\/div>\n<\/aside>\n","protected":false},"excerpt":{"rendered":"<p>Fue cuando Santiago del Moro daba los n\u00fameros parciales del versus entre Dani De Luc\u00eda y Danelik. La noche de\u00a0Gran Hermano: Generaci\u00f3n Dorada\u00a0(Telefe) fue tensa por el versus al que se hab\u00eda llegado en el final de la votaci\u00f3n. De un lado,\u00a0Daniela De Luc\u00eda\u00a0y del otro,\u00a0Danelik, ambas de grupos enfrentados. La paridad, finalmente, tuvo a [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":16407,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"rop_custom_images_group":[],"rop_custom_messages_group":[],"rop_publish_now":"initial","rop_publish_now_accounts":[],"rop_publish_now_history":[],"rop_publish_now_status":"pending","footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","enabled":false},"version":2}},"categories":[12],"tags":[],"class_list":{"0":"post-16406","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-espectaculos"},"jetpack_publicize_connections":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Un grosero error en los porcentajes de eliminaci\u00f3n expuso a \u201cGran Hermano 2026\u201d y caus\u00f3 pol\u00e9mica en las redes - CLAN ESPECTACULOS<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/radioclanfm.com\/clanespectaculos\/un-grosero-error-en-los-porcentajes-de-eliminacion-expuso-a-gran-hermano-2026-y-causo-polemica-en-las-redes\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Un grosero error en los porcentajes de eliminaci\u00f3n expuso a \u201cGran Hermano 2026\u201d y caus\u00f3 pol\u00e9mica en las redes - CLAN ESPECTACULOS\" \/>\n<meta property=\"og:description\" content=\"Fue cuando Santiago del Moro daba los n\u00fameros parciales del versus entre Dani De Luc\u00eda y Danelik. La noche de\u00a0Gran Hermano: Generaci\u00f3n Dorada\u00a0(Telefe) fue tensa por el versus al que se hab\u00eda llegado en el final de la votaci\u00f3n. De un lado,\u00a0Daniela De Luc\u00eda\u00a0y del otro,\u00a0Danelik, ambas de grupos enfrentados. La paridad, finalmente, tuvo a [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/radioclanfm.com\/clanespectaculos\/un-grosero-error-en-los-porcentajes-de-eliminacion-expuso-a-gran-hermano-2026-y-causo-polemica-en-las-redes\/\" \/>\n<meta property=\"og:site_name\" content=\"CLAN ESPECTACULOS\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/clanespectaculos\/\" \/>\n<meta property=\"article:published_time\" content=\"2026-05-12T16:28:04+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/radioclanfm.com\/clanespectaculos\/wp-content\/uploads\/sites\/2\/2026\/05\/RTGYRPod.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"900\" \/>\n\t<meta property=\"og:image:height\" content=\"504\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"E-GRUPOCLAN\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@clanespectok\" \/>\n<meta name=\"twitter:site\" content=\"@clanespectok\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"E-GRUPOCLAN\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/radioclanfm.com\\\/clanespectaculos\\\/un-grosero-error-en-los-porcentajes-de-eliminacion-expuso-a-gran-hermano-2026-y-causo-polemica-en-las-redes\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/radioclanfm.com\\\/clanespectaculos\\\/un-grosero-error-en-los-porcentajes-de-eliminacion-expuso-a-gran-hermano-2026-y-causo-polemica-en-las-redes\\\/\"},\"author\":{\"name\":\"E-GRUPOCLAN\",\"@id\":\"https:\\\/\\\/radioclanfm.com\\\/clanespectaculos\\\/#\\\/schema\\\/person\\\/9734813083303230f3ad84d99171b20c\"},\"headline\":\"Un grosero error en los porcentajes de eliminaci\u00f3n expuso a \u201cGran Hermano 2026\u201d y caus\u00f3 pol\u00e9mica en las redes\",\"datePublished\":\"2026-05-12T16:28:04+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/radioclanfm.com\\\/clanespectaculos\\\/un-grosero-error-en-los-porcentajes-de-eliminacion-expuso-a-gran-hermano-2026-y-causo-polemica-en-las-redes\\\/\"},\"wordCount\":556,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/radioclanfm.com\\\/clanespectaculos\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/radioclanfm.com\\\/clanespectaculos\\\/un-grosero-error-en-los-porcentajes-de-eliminacion-expuso-a-gran-hermano-2026-y-causo-polemica-en-las-redes\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/radioclanfm.com\\\/clanespectaculos\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2026\\\/05\\\/RTGYRPod.jpg\",\"articleSection\":[\"Espectaculos\"],\"inLanguage\":\"es-AR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/radioclanfm.com\\\/clanespectaculos\\\/un-grosero-error-en-los-porcentajes-de-eliminacion-expuso-a-gran-hermano-2026-y-causo-polemica-en-las-redes\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/radioclanfm.com\\\/clanespectaculos\\\/un-grosero-error-en-los-porcentajes-de-eliminacion-expuso-a-gran-hermano-2026-y-causo-polemica-en-las-redes\\\/\",\"url\":\"https:\\\/\\\/radioclanfm.com\\\/clanespectaculos\\\/un-grosero-error-en-los-porcentajes-de-eliminacion-expuso-a-gran-hermano-2026-y-causo-polemica-en-las-redes\\\/\",\"name\":\"Un grosero error en los porcentajes de eliminaci\u00f3n expuso a \u201cGran Hermano 2026\u201d y caus\u00f3 pol\u00e9mica en las redes - CLAN ESPECTACULOS\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/radioclanfm.com\\\/clanespectaculos\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/radioclanfm.com\\\/clanespectaculos\\\/un-grosero-error-en-los-porcentajes-de-eliminacion-expuso-a-gran-hermano-2026-y-causo-polemica-en-las-redes\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/radioclanfm.com\\\/clanespectaculos\\\/un-grosero-error-en-los-porcentajes-de-eliminacion-expuso-a-gran-hermano-2026-y-causo-polemica-en-las-redes\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/radioclanfm.com\\\/clanespectaculos\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2026\\\/05\\\/RTGYRPod.jpg\",\"datePublished\":\"2026-05-12T16:28:04+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/radioclanfm.com\\\/clanespectaculos\\\/un-grosero-error-en-los-porcentajes-de-eliminacion-expuso-a-gran-hermano-2026-y-causo-polemica-en-las-redes\\\/#breadcrumb\"},\"inLanguage\":\"es-AR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/radioclanfm.com\\\/clanespectaculos\\\/un-grosero-error-en-los-porcentajes-de-eliminacion-expuso-a-gran-hermano-2026-y-causo-polemica-en-las-redes\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es-AR\",\"@id\":\"https:\\\/\\\/radioclanfm.com\\\/clanespectaculos\\\/un-grosero-error-en-los-porcentajes-de-eliminacion-expuso-a-gran-hermano-2026-y-causo-polemica-en-las-redes\\\/#primaryimage\",\"url\":\"https:\\\/\\\/radioclanfm.com\\\/clanespectaculos\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2026\\\/05\\\/RTGYRPod.jpg\",\"contentUrl\":\"https:\\\/\\\/radioclanfm.com\\\/clanespectaculos\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2026\\\/05\\\/RTGYRPod.jpg\",\"width\":900,\"height\":504},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/radioclanfm.com\\\/clanespectaculos\\\/un-grosero-error-en-los-porcentajes-de-eliminacion-expuso-a-gran-hermano-2026-y-causo-polemica-en-las-redes\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inicio\",\"item\":\"https:\\\/\\\/radioclanfm.com\\\/clanespectaculos\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Un grosero error en los porcentajes de eliminaci\u00f3n expuso a \u201cGran Hermano 2026\u201d y caus\u00f3 pol\u00e9mica en las redes\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/radioclanfm.com\\\/clanespectaculos\\\/#website\",\"url\":\"https:\\\/\\\/radioclanfm.com\\\/clanespectaculos\\\/\",\"name\":\"CLAN ESPECTACULOS\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/radioclanfm.com\\\/clanespectaculos\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/radioclanfm.com\\\/clanespectaculos\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es-AR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/radioclanfm.com\\\/clanespectaculos\\\/#organization\",\"name\":\"CLAN ESPECTACULOS\",\"url\":\"https:\\\/\\\/radioclanfm.com\\\/clanespectaculos\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es-AR\",\"@id\":\"https:\\\/\\\/radioclanfm.com\\\/clanespectaculos\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/radioclanfm.com\\\/clanespectaculos\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2026\\\/04\\\/ChatGPT-Image-23-mar-2026-10_09_00.png\",\"contentUrl\":\"https:\\\/\\\/radioclanfm.com\\\/clanespectaculos\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2026\\\/04\\\/ChatGPT-Image-23-mar-2026-10_09_00.png\",\"width\":1024,\"height\":1024,\"caption\":\"CLAN ESPECTACULOS\"},\"image\":{\"@id\":\"https:\\\/\\\/radioclanfm.com\\\/clanespectaculos\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/clanespectaculos\\\/\",\"https:\\\/\\\/x.com\\\/clanespectok\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/radioclanfm.com\\\/clanespectaculos\\\/#\\\/schema\\\/person\\\/9734813083303230f3ad84d99171b20c\",\"name\":\"E-GRUPOCLAN\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es-AR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/af6e19837c3d6a212034a48c7b3818d2ac1826f6025df0155da5a186ad321d79?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/af6e19837c3d6a212034a48c7b3818d2ac1826f6025df0155da5a186ad321d79?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/af6e19837c3d6a212034a48c7b3818d2ac1826f6025df0155da5a186ad321d79?s=96&d=mm&r=g\",\"caption\":\"E-GRUPOCLAN\"},\"sameAs\":[\"https:\\\/\\\/radioclanfm.com\"],\"url\":\"https:\\\/\\\/radioclanfm.com\\\/clanespectaculos\\\/author\\\/admin\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Un grosero error en los porcentajes de eliminaci\u00f3n expuso a \u201cGran Hermano 2026\u201d y caus\u00f3 pol\u00e9mica en las redes - CLAN ESPECTACULOS","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/radioclanfm.com\/clanespectaculos\/un-grosero-error-en-los-porcentajes-de-eliminacion-expuso-a-gran-hermano-2026-y-causo-polemica-en-las-redes\/","og_locale":"es_ES","og_type":"article","og_title":"Un grosero error en los porcentajes de eliminaci\u00f3n expuso a \u201cGran Hermano 2026\u201d y caus\u00f3 pol\u00e9mica en las redes - CLAN ESPECTACULOS","og_description":"Fue cuando Santiago del Moro daba los n\u00fameros parciales del versus entre Dani De Luc\u00eda y Danelik. La noche de\u00a0Gran Hermano: Generaci\u00f3n Dorada\u00a0(Telefe) fue tensa por el versus al que se hab\u00eda llegado en el final de la votaci\u00f3n. De un lado,\u00a0Daniela De Luc\u00eda\u00a0y del otro,\u00a0Danelik, ambas de grupos enfrentados. La paridad, finalmente, tuvo a [&hellip;]","og_url":"https:\/\/radioclanfm.com\/clanespectaculos\/un-grosero-error-en-los-porcentajes-de-eliminacion-expuso-a-gran-hermano-2026-y-causo-polemica-en-las-redes\/","og_site_name":"CLAN ESPECTACULOS","article_publisher":"https:\/\/www.facebook.com\/clanespectaculos\/","article_published_time":"2026-05-12T16:28:04+00:00","og_image":[{"width":900,"height":504,"url":"https:\/\/radioclanfm.com\/clanespectaculos\/wp-content\/uploads\/sites\/2\/2026\/05\/RTGYRPod.jpg","type":"image\/jpeg"}],"author":"E-GRUPOCLAN","twitter_card":"summary_large_image","twitter_creator":"@clanespectok","twitter_site":"@clanespectok","twitter_misc":{"Escrito por":"E-GRUPOCLAN","Tiempo de lectura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/radioclanfm.com\/clanespectaculos\/un-grosero-error-en-los-porcentajes-de-eliminacion-expuso-a-gran-hermano-2026-y-causo-polemica-en-las-redes\/#article","isPartOf":{"@id":"https:\/\/radioclanfm.com\/clanespectaculos\/un-grosero-error-en-los-porcentajes-de-eliminacion-expuso-a-gran-hermano-2026-y-causo-polemica-en-las-redes\/"},"author":{"name":"E-GRUPOCLAN","@id":"https:\/\/radioclanfm.com\/clanespectaculos\/#\/schema\/person\/9734813083303230f3ad84d99171b20c"},"headline":"Un grosero error en los porcentajes de eliminaci\u00f3n expuso a \u201cGran Hermano 2026\u201d y caus\u00f3 pol\u00e9mica en las redes","datePublished":"2026-05-12T16:28:04+00:00","mainEntityOfPage":{"@id":"https:\/\/radioclanfm.com\/clanespectaculos\/un-grosero-error-en-los-porcentajes-de-eliminacion-expuso-a-gran-hermano-2026-y-causo-polemica-en-las-redes\/"},"wordCount":556,"commentCount":0,"publisher":{"@id":"https:\/\/radioclanfm.com\/clanespectaculos\/#organization"},"image":{"@id":"https:\/\/radioclanfm.com\/clanespectaculos\/un-grosero-error-en-los-porcentajes-de-eliminacion-expuso-a-gran-hermano-2026-y-causo-polemica-en-las-redes\/#primaryimage"},"thumbnailUrl":"https:\/\/radioclanfm.com\/clanespectaculos\/wp-content\/uploads\/sites\/2\/2026\/05\/RTGYRPod.jpg","articleSection":["Espectaculos"],"inLanguage":"es-AR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/radioclanfm.com\/clanespectaculos\/un-grosero-error-en-los-porcentajes-de-eliminacion-expuso-a-gran-hermano-2026-y-causo-polemica-en-las-redes\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/radioclanfm.com\/clanespectaculos\/un-grosero-error-en-los-porcentajes-de-eliminacion-expuso-a-gran-hermano-2026-y-causo-polemica-en-las-redes\/","url":"https:\/\/radioclanfm.com\/clanespectaculos\/un-grosero-error-en-los-porcentajes-de-eliminacion-expuso-a-gran-hermano-2026-y-causo-polemica-en-las-redes\/","name":"Un grosero error en los porcentajes de eliminaci\u00f3n expuso a \u201cGran Hermano 2026\u201d y caus\u00f3 pol\u00e9mica en las redes - CLAN ESPECTACULOS","isPartOf":{"@id":"https:\/\/radioclanfm.com\/clanespectaculos\/#website"},"primaryImageOfPage":{"@id":"https:\/\/radioclanfm.com\/clanespectaculos\/un-grosero-error-en-los-porcentajes-de-eliminacion-expuso-a-gran-hermano-2026-y-causo-polemica-en-las-redes\/#primaryimage"},"image":{"@id":"https:\/\/radioclanfm.com\/clanespectaculos\/un-grosero-error-en-los-porcentajes-de-eliminacion-expuso-a-gran-hermano-2026-y-causo-polemica-en-las-redes\/#primaryimage"},"thumbnailUrl":"https:\/\/radioclanfm.com\/clanespectaculos\/wp-content\/uploads\/sites\/2\/2026\/05\/RTGYRPod.jpg","datePublished":"2026-05-12T16:28:04+00:00","breadcrumb":{"@id":"https:\/\/radioclanfm.com\/clanespectaculos\/un-grosero-error-en-los-porcentajes-de-eliminacion-expuso-a-gran-hermano-2026-y-causo-polemica-en-las-redes\/#breadcrumb"},"inLanguage":"es-AR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/radioclanfm.com\/clanespectaculos\/un-grosero-error-en-los-porcentajes-de-eliminacion-expuso-a-gran-hermano-2026-y-causo-polemica-en-las-redes\/"]}]},{"@type":"ImageObject","inLanguage":"es-AR","@id":"https:\/\/radioclanfm.com\/clanespectaculos\/un-grosero-error-en-los-porcentajes-de-eliminacion-expuso-a-gran-hermano-2026-y-causo-polemica-en-las-redes\/#primaryimage","url":"https:\/\/radioclanfm.com\/clanespectaculos\/wp-content\/uploads\/sites\/2\/2026\/05\/RTGYRPod.jpg","contentUrl":"https:\/\/radioclanfm.com\/clanespectaculos\/wp-content\/uploads\/sites\/2\/2026\/05\/RTGYRPod.jpg","width":900,"height":504},{"@type":"BreadcrumbList","@id":"https:\/\/radioclanfm.com\/clanespectaculos\/un-grosero-error-en-los-porcentajes-de-eliminacion-expuso-a-gran-hermano-2026-y-causo-polemica-en-las-redes\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inicio","item":"https:\/\/radioclanfm.com\/clanespectaculos\/"},{"@type":"ListItem","position":2,"name":"Un grosero error en los porcentajes de eliminaci\u00f3n expuso a \u201cGran Hermano 2026\u201d y caus\u00f3 pol\u00e9mica en las redes"}]},{"@type":"WebSite","@id":"https:\/\/radioclanfm.com\/clanespectaculos\/#website","url":"https:\/\/radioclanfm.com\/clanespectaculos\/","name":"CLAN ESPECTACULOS","description":"","publisher":{"@id":"https:\/\/radioclanfm.com\/clanespectaculos\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/radioclanfm.com\/clanespectaculos\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es-AR"},{"@type":"Organization","@id":"https:\/\/radioclanfm.com\/clanespectaculos\/#organization","name":"CLAN ESPECTACULOS","url":"https:\/\/radioclanfm.com\/clanespectaculos\/","logo":{"@type":"ImageObject","inLanguage":"es-AR","@id":"https:\/\/radioclanfm.com\/clanespectaculos\/#\/schema\/logo\/image\/","url":"https:\/\/radioclanfm.com\/clanespectaculos\/wp-content\/uploads\/sites\/2\/2026\/04\/ChatGPT-Image-23-mar-2026-10_09_00.png","contentUrl":"https:\/\/radioclanfm.com\/clanespectaculos\/wp-content\/uploads\/sites\/2\/2026\/04\/ChatGPT-Image-23-mar-2026-10_09_00.png","width":1024,"height":1024,"caption":"CLAN ESPECTACULOS"},"image":{"@id":"https:\/\/radioclanfm.com\/clanespectaculos\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/clanespectaculos\/","https:\/\/x.com\/clanespectok"]},{"@type":"Person","@id":"https:\/\/radioclanfm.com\/clanespectaculos\/#\/schema\/person\/9734813083303230f3ad84d99171b20c","name":"E-GRUPOCLAN","image":{"@type":"ImageObject","inLanguage":"es-AR","@id":"https:\/\/secure.gravatar.com\/avatar\/af6e19837c3d6a212034a48c7b3818d2ac1826f6025df0155da5a186ad321d79?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/af6e19837c3d6a212034a48c7b3818d2ac1826f6025df0155da5a186ad321d79?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/af6e19837c3d6a212034a48c7b3818d2ac1826f6025df0155da5a186ad321d79?s=96&d=mm&r=g","caption":"E-GRUPOCLAN"},"sameAs":["https:\/\/radioclanfm.com"],"url":"https:\/\/radioclanfm.com\/clanespectaculos\/author\/admin\/"}]}},"_links":{"self":[{"href":"https:\/\/radioclanfm.com\/clanespectaculos\/wp-json\/wp\/v2\/posts\/16406","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/radioclanfm.com\/clanespectaculos\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/radioclanfm.com\/clanespectaculos\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/radioclanfm.com\/clanespectaculos\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/radioclanfm.com\/clanespectaculos\/wp-json\/wp\/v2\/comments?post=16406"}],"version-history":[{"count":1,"href":"https:\/\/radioclanfm.com\/clanespectaculos\/wp-json\/wp\/v2\/posts\/16406\/revisions"}],"predecessor-version":[{"id":16408,"href":"https:\/\/radioclanfm.com\/clanespectaculos\/wp-json\/wp\/v2\/posts\/16406\/revisions\/16408"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/radioclanfm.com\/clanespectaculos\/wp-json\/wp\/v2\/media\/16407"}],"wp:attachment":[{"href":"https:\/\/radioclanfm.com\/clanespectaculos\/wp-json\/wp\/v2\/media?parent=16406"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/radioclanfm.com\/clanespectaculos\/wp-json\/wp\/v2\/categories?post=16406"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/radioclanfm.com\/clanespectaculos\/wp-json\/wp\/v2\/tags?post=16406"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}