{"id":16237,"date":"2026-05-05T11:12:26","date_gmt":"2026-05-05T14:12:26","guid":{"rendered":"https:\/\/radioclanfm.com\/clanespectaculos\/?p=16237"},"modified":"2026-05-05T11:12:26","modified_gmt":"2026-05-05T14:12:26","slug":"filtraron-una-escandalosa-version-sobre-la-separacion-de-pampita-y-martin-pepa-el-se-mando-una","status":"publish","type":"post","link":"https:\/\/radioclanfm.com\/clanespectaculos\/filtraron-una-escandalosa-version-sobre-la-separacion-de-pampita-y-martin-pepa-el-se-mando-una\/","title":{"rendered":"Filtraron una escandalosa versi\u00f3n sobre la separaci\u00f3n de Pampita y Mart\u00edn Pepa: \u201c\u00c9l se mand\u00f3 una\u201d"},"content":{"rendered":"<p>Despu\u00e9s de que se confirmara la ruptura, se conocieron detalles y trascendi\u00f3 que la modelo est\u00e1 muy triste.<\/p>\n<div class=\"col-content\"><main class=\"col-content\"><\/p>\n<div class=\"default-article-color article__body article__article\">\n<p class=\"paragraph font__body-regular\"><b>Pampita<\/b>\u00a0y\u00a0<b>Mart\u00edn Pepa<\/b>\u00a0se separaron despu\u00e9s de un a\u00f1o de relaci\u00f3n. En medio de los rumores y las especulaciones,\u00a0<b>Yanina Latorre<\/b><b>\u00a0sorprendi\u00f3 con una revelaci\u00f3n acerca de los motivos de la ruptura.<\/b><\/p>\n<div id=\"ad-slot-infeed\" class=\"infeed-container ad-slot-infeed ad-slot\" data-adtype=\"infeed\" data-lazyload=\"1\" data-google-query-id=\"CO7BjvGpopQDFS4ouQYdCYMRmw\">\n<div id=\"google_ads_iframe_\/113951150\/tn-arc\/nota\/infeed_0__container__\"><\/div>\n<\/div>\n<p class=\"paragraph font__body-regular\">Al aire de\u00a0<i>SQP\u00a0<\/i>(<i>Am\u00e9rica<\/i>), la conductora repas\u00f3 la informaci\u00f3n que hay hasta el momento sobre la crisis entre la top y el polista. \u201cFinalmente, logr\u00e9 la confirmaci\u00f3n de Pampita. (&#8230;) Una persona habl\u00f3 con ella y ella le confirm\u00f3 que\u00a0estaba muy triste y que se iba a ahogar penas y a pasar unos d\u00edas en Miami\u201d, se\u00f1al\u00f3.<\/p>\n<div data-mrf-experience=\"IL_RNrGCM52Q_ui4aMax3fibg\"><\/div>\n<p class=\"paragraph font__body-regular\">Acto seguido, sum\u00f3 nueva data: \u201cTengo otra persona que habl\u00f3 con ella y estoy en condiciones de decir que<b>\u00a0est\u00e1 muy triste porque lo habr\u00eda agarrado en algo a Mart\u00edn Pepa\u201d.<\/b><\/p>\n<figure class=\"\" data-testid=\"figure-testid\">\n<div class=\"aspect_ratio__container\"><picture class=\"responsive-image\"><source srcset=\"https:\/\/tn.com.ar\/resizer\/v2\/pampita-y-martin-pepa-en-una-noche-romantica-foto-instagrampampitaoficial-36KTQACE65FKTB45ER63OWUJQM.jpeg?auth=dc90bf07c1f39173ea3079423e0d60cccb1dfcce3c0c854212f2286b9e551490&amp;width=767\" type=\"image\/jpg\" media=\"(max-width: 728px)\" \/><source srcset=\"https:\/\/tn.com.ar\/resizer\/v2\/pampita-y-martin-pepa-en-una-noche-romantica-foto-instagrampampitaoficial-36KTQACE65FKTB45ER63OWUJQM.jpeg?auth=dc90bf07c1f39173ea3079423e0d60cccb1dfcce3c0c854212f2286b9e551490&amp;width=1023\" type=\"image\/jpg\" media=\"(max-width: 1023px)\" \/><source srcset=\"https:\/\/tn.com.ar\/resizer\/v2\/pampita-y-martin-pepa-en-una-noche-romantica-foto-instagrampampitaoficial-36KTQACE65FKTB45ER63OWUJQM.jpeg?auth=dc90bf07c1f39173ea3079423e0d60cccb1dfcce3c0c854212f2286b9e551490&amp;width=1440\" type=\"image\/jpg\" \/><img loading=\"lazy\" decoding=\"async\" class=\"image content-image image_placeholder\" src=\"https:\/\/tn.com.ar\/resizer\/v2\/pampita-y-martin-pepa-en-una-noche-romantica-foto-instagrampampitaoficial-36KTQACE65FKTB45ER63OWUJQM.jpeg?auth=dc90bf07c1f39173ea3079423e0d60cccb1dfcce3c0c854212f2286b9e551490&amp;width=767\" alt=\"Pampita y Mart\u00edn Pepa en una noche rom\u00e1ntica. (Foto: Instagram\/pampitaoficial)\" width=\"767\" height=\"614\" data-testid=\"loading-testid\" \/><\/picture><\/div><figcaption class=\"caption_image\" data-testid=\"figcaption-testid\">\n<div class=\"image_caption \">Pampita y Mart\u00edn Pepa en una noche rom\u00e1ntica. (Foto: Instagram\/pampitaoficial)<\/div>\n<\/figcaption><\/figure>\n<p class=\"paragraph font__body-regular\"><b>\u201cNo s\u00e9 qu\u00e9 es el algo&#8230; No s\u00e9 si es un enga\u00f1o, puede ser una mentira o que omiti\u00f3 contarle algo\u201d<\/b>, aclar\u00f3. Y sostuvo: \u201cPorque cuando vos agarr\u00e1s a alguien en algo, no siempre es un cuerno. Habr\u00e1 otras mentiras, otras traiciones\u201d.<\/p>\n<p class=\"paragraph font__body-regular\">Sobre el presente de la modelo, precis\u00f3: \u201cElla de Miami se fue a Nueva York y est\u00e1 en un viaje con amigas y amigos, se est\u00e1 divirtiendo\u201d. \u201cSe enter\u00f3 de todo lo que yo cont\u00e9 y estaba enajenada tratando de averiguar qui\u00e9n me lo hab\u00eda dicho\u201d, asegur\u00f3.<\/p>\n<p class=\"paragraph font__body-regular\">A modo de cierre, Latorre lanz\u00f3: \u201cEso es lo que s\u00e9. Est\u00e1 ahogando penas. No s\u00e9 por qu\u00e9 no contesta.\u00a0<b>Algo le hizo \u00e9l, pero no puedo decir que sea un enga\u00f1o amoroso. O sea, dijo \u2018se mand\u00f3 una y estoy muy triste\u2019\u201d<\/b>.<\/p>\n<h2 class=\"font--primary font__display\">Cu\u00e1les fueron los indicios que dejaron al descubierto la crisis entre Pampita y Mart\u00edn Pepa<\/h2>\n<p class=\"paragraph font__body-regular\">El mi\u00e9rcoles, Yanina Latorre cont\u00f3 que dos personas le confirmaron la ruptura y que el resto del entorno de la modelo no le respondi\u00f3.<\/p>\n<p class=\"paragraph font__body-regular\">\u201cNos pusimos a buscar la ruta del like.<b>\u00a0\u00c9l hoy cerr\u00f3 sus redes.<\/b>\u00a0Ten\u00eda el Instagram abierto y de la nada lo puso en privado\u201d, destac\u00f3. Y remarc\u00f3:\u00a0<b>\u201cEl \u00faltimo like de \u00e9l es de los primeros d\u00edas de abril\u201d.<\/b><\/p>\n<p class=\"paragraph font__body-regular\">Otra de las cuestiones que se\u00f1al\u00f3 fueron las declaraciones que dio el domingo en el marco de los Mart\u00edn Fierro de Moda al ser consultada sobre el amor. \u201cSiempre estoy enamorada. Ya me conocen, soy una mujer enamorada de la vida\u201d.<\/p>\n<figure class=\"\" data-testid=\"figure-testid\">\n<div class=\"aspect_ratio__container\"><picture class=\"responsive-image\"><source srcset=\"https:\/\/tn.com.ar\/resizer\/v2\/el-posteo-de-pampita-con-martin-pepa-foto-instagrampampitaoficial-75JI33GGGVFSRFRS2ZREUPCJVY.jpeg?auth=3a544effa9640f747c78b7d3d876580c4fde5bffc6fc0c29ce2e826406875243&amp;width=767\" type=\"image\/jpg\" media=\"(max-width: 728px)\" \/><source srcset=\"https:\/\/tn.com.ar\/resizer\/v2\/el-posteo-de-pampita-con-martin-pepa-foto-instagrampampitaoficial-75JI33GGGVFSRFRS2ZREUPCJVY.jpeg?auth=3a544effa9640f747c78b7d3d876580c4fde5bffc6fc0c29ce2e826406875243&amp;width=1023\" type=\"image\/jpg\" media=\"(max-width: 1023px)\" \/><source srcset=\"https:\/\/tn.com.ar\/resizer\/v2\/el-posteo-de-pampita-con-martin-pepa-foto-instagrampampitaoficial-75JI33GGGVFSRFRS2ZREUPCJVY.jpeg?auth=3a544effa9640f747c78b7d3d876580c4fde5bffc6fc0c29ce2e826406875243&amp;width=1440\" type=\"image\/jpg\" \/><img loading=\"lazy\" decoding=\"async\" class=\"image content-image image_placeholder\" src=\"https:\/\/tn.com.ar\/resizer\/v2\/el-posteo-de-pampita-con-martin-pepa-foto-instagrampampitaoficial-75JI33GGGVFSRFRS2ZREUPCJVY.jpeg?auth=3a544effa9640f747c78b7d3d876580c4fde5bffc6fc0c29ce2e826406875243&amp;width=767\" alt=\"El posteo de Pampita con Mart\u00edn Pepa. (Foto: Instagram\/pampitaoficial)\" width=\"767\" height=\"1346\" data-testid=\"loading-testid\" \/><\/picture><\/div><figcaption class=\"caption_image\" data-testid=\"figcaption-testid\">\n<div class=\"image_caption \">El posteo de Pampita con Mart\u00edn Pepa. (Foto: Instagram\/pampitaoficial)<\/div>\n<\/figcaption><\/figure>\n<p class=\"paragraph font__body-regular\">En la misma sinton\u00eda, Majo Martino cont\u00f3 que Pampita no le contest\u00f3, pero dos de sus amigas s\u00ed \u201cUna me dijo \u2018cero. Est\u00e1n rebien\u2019. Pero la otra me puso \u2018parece\u2019\u201d, detall\u00f3.<\/p>\n<p class=\"paragraph font__body-regular\">Adem\u00e1s, repararon en\u00a0la dedicatoria de Pampita al recibir la estatuilla por Mejor estilo en Redes. \u201c<b>A mis hijos que est\u00e1n mirando y a mi hija en el cielo<\/b>. A los grandes amores de mi vida, Blanca, Bautista, Beltr\u00e1n, Benicio y Anita, los amo\u201d, expres\u00f3 sin nombrar a su pareja.<\/p>\n<div class=\"genoa_video raw relative\">\n<div class=\"video_placeholder\">\n<div class=\"aspect_ratio__container\"><picture class=\"responsive-image\"><source srcset=\"https:\/\/tn.com.ar\/resizer\/v2\/https%3A%2F%2Fthumbs.vodgc.net%2F1-14-tEpVqg1777503037218-1777503628.jpg?auth=3d668c956d22e579de421362ec0c4ee31f278d8863e93531c096d323b3335a2d&amp;width=767\" type=\"image\/jpg\" media=\"(max-width: 728px)\" \/><source srcset=\"https:\/\/tn.com.ar\/resizer\/v2\/https%3A%2F%2Fthumbs.vodgc.net%2F1-14-tEpVqg1777503037218-1777503628.jpg?auth=3d668c956d22e579de421362ec0c4ee31f278d8863e93531c096d323b3335a2d&amp;width=1023\" type=\"image\/jpg\" media=\"(max-width: 1023px)\" \/><source srcset=\"https:\/\/tn.com.ar\/resizer\/v2\/https%3A%2F%2Fthumbs.vodgc.net%2F1-14-tEpVqg1777503037218-1777503628.jpg?auth=3d668c956d22e579de421362ec0c4ee31f278d8863e93531c096d323b3335a2d&amp;width=1440\" type=\"image\/jpg\" \/><\/picture><\/div>\n<p><button type=\"button\" data-testid=\"video-placeholder-button\"><\/button><\/div>\n<\/div>\n<div class=\"genoa_description font__body-regular\"><\/div>\n<p class=\"paragraph font__body-regular\">A modo de cierre, Latorre sum\u00f3 un dato m\u00e1s: \u201cHoy Pampita grab\u00f3 una nota con Carmen Barbieri (&#8230;). Cuando la modelo pregunt\u00f3 c\u00f3mo estaba en el amor, la capoc\u00f3mica le repregunt\u00f3. \u00bfY sab\u00e9n lo que le dice Pampita? M\u00e1s o menos&#8221;.<\/p>\n<\/div>\n<p><\/main><\/div>\n<aside class=\"col-right-rail right-rail\">\n<div id=\"parent-ad-slot-caja\" class=\"ad-container caja_ad \">\n<div class=\"ad-content\"><\/div>\n<\/div>\n<\/aside>\n","protected":false},"excerpt":{"rendered":"<p>Despu\u00e9s de que se confirmara la ruptura, se conocieron detalles y trascendi\u00f3 que la modelo est\u00e1 muy triste. Pampita\u00a0y\u00a0Mart\u00edn Pepa\u00a0se separaron despu\u00e9s de un a\u00f1o de relaci\u00f3n. En medio de los rumores y las especulaciones,\u00a0Yanina Latorre\u00a0sorprendi\u00f3 con una revelaci\u00f3n acerca de los motivos de la ruptura. Al aire de\u00a0SQP\u00a0(Am\u00e9rica), la conductora repas\u00f3 la informaci\u00f3n que [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":16238,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"rop_custom_images_group":[],"rop_custom_messages_group":[],"rop_publish_now":"initial","rop_publish_now_accounts":[],"rop_publish_now_history":[],"rop_publish_now_status":"pending","footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","enabled":false},"version":2}},"categories":[12],"tags":[],"class_list":{"0":"post-16237","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-espectaculos"},"jetpack_publicize_connections":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Filtraron una escandalosa versi\u00f3n sobre la separaci\u00f3n de Pampita y Mart\u00edn Pepa: \u201c\u00c9l se mand\u00f3 una\u201d - CLAN ESPECTACULOS<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/radioclanfm.com\/clanespectaculos\/filtraron-una-escandalosa-version-sobre-la-separacion-de-pampita-y-martin-pepa-el-se-mando-una\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Filtraron una escandalosa versi\u00f3n sobre la separaci\u00f3n de Pampita y Mart\u00edn Pepa: \u201c\u00c9l se mand\u00f3 una\u201d - CLAN ESPECTACULOS\" \/>\n<meta property=\"og:description\" content=\"Despu\u00e9s de que se confirmara la ruptura, se conocieron detalles y trascendi\u00f3 que la modelo est\u00e1 muy triste. Pampita\u00a0y\u00a0Mart\u00edn Pepa\u00a0se separaron despu\u00e9s de un a\u00f1o de relaci\u00f3n. En medio de los rumores y las especulaciones,\u00a0Yanina Latorre\u00a0sorprendi\u00f3 con una revelaci\u00f3n acerca de los motivos de la ruptura. Al aire de\u00a0SQP\u00a0(Am\u00e9rica), la conductora repas\u00f3 la informaci\u00f3n que [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/radioclanfm.com\/clanespectaculos\/filtraron-una-escandalosa-version-sobre-la-separacion-de-pampita-y-martin-pepa-el-se-mando-una\/\" \/>\n<meta property=\"og:site_name\" content=\"CLAN ESPECTACULOS\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/clanespectaculos\/\" \/>\n<meta property=\"article:published_time\" content=\"2026-05-05T14:12:26+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/radioclanfm.com\/clanespectaculos\/wp-content\/uploads\/sites\/2\/2026\/05\/Iyydbp5H.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"900\" \/>\n\t<meta property=\"og:image:height\" content=\"505\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"E-GRUPOCLAN\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@clanespectok\" \/>\n<meta name=\"twitter:site\" content=\"@clanespectok\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"E-GRUPOCLAN\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/radioclanfm.com\\\/clanespectaculos\\\/filtraron-una-escandalosa-version-sobre-la-separacion-de-pampita-y-martin-pepa-el-se-mando-una\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/radioclanfm.com\\\/clanespectaculos\\\/filtraron-una-escandalosa-version-sobre-la-separacion-de-pampita-y-martin-pepa-el-se-mando-una\\\/\"},\"author\":{\"name\":\"E-GRUPOCLAN\",\"@id\":\"https:\\\/\\\/radioclanfm.com\\\/clanespectaculos\\\/#\\\/schema\\\/person\\\/9734813083303230f3ad84d99171b20c\"},\"headline\":\"Filtraron una escandalosa versi\u00f3n sobre la separaci\u00f3n de Pampita y Mart\u00edn Pepa: \u201c\u00c9l se mand\u00f3 una\u201d\",\"datePublished\":\"2026-05-05T14:12:26+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/radioclanfm.com\\\/clanespectaculos\\\/filtraron-una-escandalosa-version-sobre-la-separacion-de-pampita-y-martin-pepa-el-se-mando-una\\\/\"},\"wordCount\":591,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/radioclanfm.com\\\/clanespectaculos\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/radioclanfm.com\\\/clanespectaculos\\\/filtraron-una-escandalosa-version-sobre-la-separacion-de-pampita-y-martin-pepa-el-se-mando-una\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/radioclanfm.com\\\/clanespectaculos\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2026\\\/05\\\/Iyydbp5H.jpg\",\"articleSection\":[\"Espectaculos\"],\"inLanguage\":\"es-AR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/radioclanfm.com\\\/clanespectaculos\\\/filtraron-una-escandalosa-version-sobre-la-separacion-de-pampita-y-martin-pepa-el-se-mando-una\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/radioclanfm.com\\\/clanespectaculos\\\/filtraron-una-escandalosa-version-sobre-la-separacion-de-pampita-y-martin-pepa-el-se-mando-una\\\/\",\"url\":\"https:\\\/\\\/radioclanfm.com\\\/clanespectaculos\\\/filtraron-una-escandalosa-version-sobre-la-separacion-de-pampita-y-martin-pepa-el-se-mando-una\\\/\",\"name\":\"Filtraron una escandalosa versi\u00f3n sobre la separaci\u00f3n de Pampita y Mart\u00edn Pepa: \u201c\u00c9l se mand\u00f3 una\u201d - CLAN ESPECTACULOS\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/radioclanfm.com\\\/clanespectaculos\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/radioclanfm.com\\\/clanespectaculos\\\/filtraron-una-escandalosa-version-sobre-la-separacion-de-pampita-y-martin-pepa-el-se-mando-una\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/radioclanfm.com\\\/clanespectaculos\\\/filtraron-una-escandalosa-version-sobre-la-separacion-de-pampita-y-martin-pepa-el-se-mando-una\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/radioclanfm.com\\\/clanespectaculos\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2026\\\/05\\\/Iyydbp5H.jpg\",\"datePublished\":\"2026-05-05T14:12:26+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/radioclanfm.com\\\/clanespectaculos\\\/filtraron-una-escandalosa-version-sobre-la-separacion-de-pampita-y-martin-pepa-el-se-mando-una\\\/#breadcrumb\"},\"inLanguage\":\"es-AR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/radioclanfm.com\\\/clanespectaculos\\\/filtraron-una-escandalosa-version-sobre-la-separacion-de-pampita-y-martin-pepa-el-se-mando-una\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es-AR\",\"@id\":\"https:\\\/\\\/radioclanfm.com\\\/clanespectaculos\\\/filtraron-una-escandalosa-version-sobre-la-separacion-de-pampita-y-martin-pepa-el-se-mando-una\\\/#primaryimage\",\"url\":\"https:\\\/\\\/radioclanfm.com\\\/clanespectaculos\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2026\\\/05\\\/Iyydbp5H.jpg\",\"contentUrl\":\"https:\\\/\\\/radioclanfm.com\\\/clanespectaculos\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2026\\\/05\\\/Iyydbp5H.jpg\",\"width\":900,\"height\":505},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/radioclanfm.com\\\/clanespectaculos\\\/filtraron-una-escandalosa-version-sobre-la-separacion-de-pampita-y-martin-pepa-el-se-mando-una\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inicio\",\"item\":\"https:\\\/\\\/radioclanfm.com\\\/clanespectaculos\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Filtraron una escandalosa versi\u00f3n sobre la separaci\u00f3n de Pampita y Mart\u00edn Pepa: \u201c\u00c9l se mand\u00f3 una\u201d\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/radioclanfm.com\\\/clanespectaculos\\\/#website\",\"url\":\"https:\\\/\\\/radioclanfm.com\\\/clanespectaculos\\\/\",\"name\":\"CLAN ESPECTACULOS\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/radioclanfm.com\\\/clanespectaculos\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/radioclanfm.com\\\/clanespectaculos\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es-AR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/radioclanfm.com\\\/clanespectaculos\\\/#organization\",\"name\":\"CLAN ESPECTACULOS\",\"url\":\"https:\\\/\\\/radioclanfm.com\\\/clanespectaculos\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es-AR\",\"@id\":\"https:\\\/\\\/radioclanfm.com\\\/clanespectaculos\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/radioclanfm.com\\\/clanespectaculos\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2026\\\/04\\\/ChatGPT-Image-23-mar-2026-10_09_00.png\",\"contentUrl\":\"https:\\\/\\\/radioclanfm.com\\\/clanespectaculos\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2026\\\/04\\\/ChatGPT-Image-23-mar-2026-10_09_00.png\",\"width\":1024,\"height\":1024,\"caption\":\"CLAN ESPECTACULOS\"},\"image\":{\"@id\":\"https:\\\/\\\/radioclanfm.com\\\/clanespectaculos\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/clanespectaculos\\\/\",\"https:\\\/\\\/x.com\\\/clanespectok\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/radioclanfm.com\\\/clanespectaculos\\\/#\\\/schema\\\/person\\\/9734813083303230f3ad84d99171b20c\",\"name\":\"E-GRUPOCLAN\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es-AR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/af6e19837c3d6a212034a48c7b3818d2ac1826f6025df0155da5a186ad321d79?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/af6e19837c3d6a212034a48c7b3818d2ac1826f6025df0155da5a186ad321d79?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/af6e19837c3d6a212034a48c7b3818d2ac1826f6025df0155da5a186ad321d79?s=96&d=mm&r=g\",\"caption\":\"E-GRUPOCLAN\"},\"sameAs\":[\"https:\\\/\\\/radioclanfm.com\"],\"url\":\"https:\\\/\\\/radioclanfm.com\\\/clanespectaculos\\\/author\\\/admin\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Filtraron una escandalosa versi\u00f3n sobre la separaci\u00f3n de Pampita y Mart\u00edn Pepa: \u201c\u00c9l se mand\u00f3 una\u201d - CLAN ESPECTACULOS","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/radioclanfm.com\/clanespectaculos\/filtraron-una-escandalosa-version-sobre-la-separacion-de-pampita-y-martin-pepa-el-se-mando-una\/","og_locale":"es_ES","og_type":"article","og_title":"Filtraron una escandalosa versi\u00f3n sobre la separaci\u00f3n de Pampita y Mart\u00edn Pepa: \u201c\u00c9l se mand\u00f3 una\u201d - CLAN ESPECTACULOS","og_description":"Despu\u00e9s de que se confirmara la ruptura, se conocieron detalles y trascendi\u00f3 que la modelo est\u00e1 muy triste. Pampita\u00a0y\u00a0Mart\u00edn Pepa\u00a0se separaron despu\u00e9s de un a\u00f1o de relaci\u00f3n. En medio de los rumores y las especulaciones,\u00a0Yanina Latorre\u00a0sorprendi\u00f3 con una revelaci\u00f3n acerca de los motivos de la ruptura. Al aire de\u00a0SQP\u00a0(Am\u00e9rica), la conductora repas\u00f3 la informaci\u00f3n que [&hellip;]","og_url":"https:\/\/radioclanfm.com\/clanespectaculos\/filtraron-una-escandalosa-version-sobre-la-separacion-de-pampita-y-martin-pepa-el-se-mando-una\/","og_site_name":"CLAN ESPECTACULOS","article_publisher":"https:\/\/www.facebook.com\/clanespectaculos\/","article_published_time":"2026-05-05T14:12:26+00:00","og_image":[{"width":900,"height":505,"url":"https:\/\/radioclanfm.com\/clanespectaculos\/wp-content\/uploads\/sites\/2\/2026\/05\/Iyydbp5H.jpg","type":"image\/jpeg"}],"author":"E-GRUPOCLAN","twitter_card":"summary_large_image","twitter_creator":"@clanespectok","twitter_site":"@clanespectok","twitter_misc":{"Escrito por":"E-GRUPOCLAN","Tiempo de lectura":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/radioclanfm.com\/clanespectaculos\/filtraron-una-escandalosa-version-sobre-la-separacion-de-pampita-y-martin-pepa-el-se-mando-una\/#article","isPartOf":{"@id":"https:\/\/radioclanfm.com\/clanespectaculos\/filtraron-una-escandalosa-version-sobre-la-separacion-de-pampita-y-martin-pepa-el-se-mando-una\/"},"author":{"name":"E-GRUPOCLAN","@id":"https:\/\/radioclanfm.com\/clanespectaculos\/#\/schema\/person\/9734813083303230f3ad84d99171b20c"},"headline":"Filtraron una escandalosa versi\u00f3n sobre la separaci\u00f3n de Pampita y Mart\u00edn Pepa: \u201c\u00c9l se mand\u00f3 una\u201d","datePublished":"2026-05-05T14:12:26+00:00","mainEntityOfPage":{"@id":"https:\/\/radioclanfm.com\/clanespectaculos\/filtraron-una-escandalosa-version-sobre-la-separacion-de-pampita-y-martin-pepa-el-se-mando-una\/"},"wordCount":591,"commentCount":0,"publisher":{"@id":"https:\/\/radioclanfm.com\/clanespectaculos\/#organization"},"image":{"@id":"https:\/\/radioclanfm.com\/clanespectaculos\/filtraron-una-escandalosa-version-sobre-la-separacion-de-pampita-y-martin-pepa-el-se-mando-una\/#primaryimage"},"thumbnailUrl":"https:\/\/radioclanfm.com\/clanespectaculos\/wp-content\/uploads\/sites\/2\/2026\/05\/Iyydbp5H.jpg","articleSection":["Espectaculos"],"inLanguage":"es-AR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/radioclanfm.com\/clanespectaculos\/filtraron-una-escandalosa-version-sobre-la-separacion-de-pampita-y-martin-pepa-el-se-mando-una\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/radioclanfm.com\/clanespectaculos\/filtraron-una-escandalosa-version-sobre-la-separacion-de-pampita-y-martin-pepa-el-se-mando-una\/","url":"https:\/\/radioclanfm.com\/clanespectaculos\/filtraron-una-escandalosa-version-sobre-la-separacion-de-pampita-y-martin-pepa-el-se-mando-una\/","name":"Filtraron una escandalosa versi\u00f3n sobre la separaci\u00f3n de Pampita y Mart\u00edn Pepa: \u201c\u00c9l se mand\u00f3 una\u201d - CLAN ESPECTACULOS","isPartOf":{"@id":"https:\/\/radioclanfm.com\/clanespectaculos\/#website"},"primaryImageOfPage":{"@id":"https:\/\/radioclanfm.com\/clanespectaculos\/filtraron-una-escandalosa-version-sobre-la-separacion-de-pampita-y-martin-pepa-el-se-mando-una\/#primaryimage"},"image":{"@id":"https:\/\/radioclanfm.com\/clanespectaculos\/filtraron-una-escandalosa-version-sobre-la-separacion-de-pampita-y-martin-pepa-el-se-mando-una\/#primaryimage"},"thumbnailUrl":"https:\/\/radioclanfm.com\/clanespectaculos\/wp-content\/uploads\/sites\/2\/2026\/05\/Iyydbp5H.jpg","datePublished":"2026-05-05T14:12:26+00:00","breadcrumb":{"@id":"https:\/\/radioclanfm.com\/clanespectaculos\/filtraron-una-escandalosa-version-sobre-la-separacion-de-pampita-y-martin-pepa-el-se-mando-una\/#breadcrumb"},"inLanguage":"es-AR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/radioclanfm.com\/clanespectaculos\/filtraron-una-escandalosa-version-sobre-la-separacion-de-pampita-y-martin-pepa-el-se-mando-una\/"]}]},{"@type":"ImageObject","inLanguage":"es-AR","@id":"https:\/\/radioclanfm.com\/clanespectaculos\/filtraron-una-escandalosa-version-sobre-la-separacion-de-pampita-y-martin-pepa-el-se-mando-una\/#primaryimage","url":"https:\/\/radioclanfm.com\/clanespectaculos\/wp-content\/uploads\/sites\/2\/2026\/05\/Iyydbp5H.jpg","contentUrl":"https:\/\/radioclanfm.com\/clanespectaculos\/wp-content\/uploads\/sites\/2\/2026\/05\/Iyydbp5H.jpg","width":900,"height":505},{"@type":"BreadcrumbList","@id":"https:\/\/radioclanfm.com\/clanespectaculos\/filtraron-una-escandalosa-version-sobre-la-separacion-de-pampita-y-martin-pepa-el-se-mando-una\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inicio","item":"https:\/\/radioclanfm.com\/clanespectaculos\/"},{"@type":"ListItem","position":2,"name":"Filtraron una escandalosa versi\u00f3n sobre la separaci\u00f3n de Pampita y Mart\u00edn Pepa: \u201c\u00c9l se mand\u00f3 una\u201d"}]},{"@type":"WebSite","@id":"https:\/\/radioclanfm.com\/clanespectaculos\/#website","url":"https:\/\/radioclanfm.com\/clanespectaculos\/","name":"CLAN ESPECTACULOS","description":"","publisher":{"@id":"https:\/\/radioclanfm.com\/clanespectaculos\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/radioclanfm.com\/clanespectaculos\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es-AR"},{"@type":"Organization","@id":"https:\/\/radioclanfm.com\/clanespectaculos\/#organization","name":"CLAN ESPECTACULOS","url":"https:\/\/radioclanfm.com\/clanespectaculos\/","logo":{"@type":"ImageObject","inLanguage":"es-AR","@id":"https:\/\/radioclanfm.com\/clanespectaculos\/#\/schema\/logo\/image\/","url":"https:\/\/radioclanfm.com\/clanespectaculos\/wp-content\/uploads\/sites\/2\/2026\/04\/ChatGPT-Image-23-mar-2026-10_09_00.png","contentUrl":"https:\/\/radioclanfm.com\/clanespectaculos\/wp-content\/uploads\/sites\/2\/2026\/04\/ChatGPT-Image-23-mar-2026-10_09_00.png","width":1024,"height":1024,"caption":"CLAN ESPECTACULOS"},"image":{"@id":"https:\/\/radioclanfm.com\/clanespectaculos\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/clanespectaculos\/","https:\/\/x.com\/clanespectok"]},{"@type":"Person","@id":"https:\/\/radioclanfm.com\/clanespectaculos\/#\/schema\/person\/9734813083303230f3ad84d99171b20c","name":"E-GRUPOCLAN","image":{"@type":"ImageObject","inLanguage":"es-AR","@id":"https:\/\/secure.gravatar.com\/avatar\/af6e19837c3d6a212034a48c7b3818d2ac1826f6025df0155da5a186ad321d79?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/af6e19837c3d6a212034a48c7b3818d2ac1826f6025df0155da5a186ad321d79?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/af6e19837c3d6a212034a48c7b3818d2ac1826f6025df0155da5a186ad321d79?s=96&d=mm&r=g","caption":"E-GRUPOCLAN"},"sameAs":["https:\/\/radioclanfm.com"],"url":"https:\/\/radioclanfm.com\/clanespectaculos\/author\/admin\/"}]}},"_links":{"self":[{"href":"https:\/\/radioclanfm.com\/clanespectaculos\/wp-json\/wp\/v2\/posts\/16237","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/radioclanfm.com\/clanespectaculos\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/radioclanfm.com\/clanespectaculos\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/radioclanfm.com\/clanespectaculos\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/radioclanfm.com\/clanespectaculos\/wp-json\/wp\/v2\/comments?post=16237"}],"version-history":[{"count":1,"href":"https:\/\/radioclanfm.com\/clanespectaculos\/wp-json\/wp\/v2\/posts\/16237\/revisions"}],"predecessor-version":[{"id":16239,"href":"https:\/\/radioclanfm.com\/clanespectaculos\/wp-json\/wp\/v2\/posts\/16237\/revisions\/16239"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/radioclanfm.com\/clanespectaculos\/wp-json\/wp\/v2\/media\/16238"}],"wp:attachment":[{"href":"https:\/\/radioclanfm.com\/clanespectaculos\/wp-json\/wp\/v2\/media?parent=16237"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/radioclanfm.com\/clanespectaculos\/wp-json\/wp\/v2\/categories?post=16237"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/radioclanfm.com\/clanespectaculos\/wp-json\/wp\/v2\/tags?post=16237"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}