{"id":16053,"date":"2026-05-02T20:45:14","date_gmt":"2026-05-02T23:45:14","guid":{"rendered":"https:\/\/radioclanfm.com\/clanespectaculos\/?p=16053"},"modified":"2026-05-02T20:45:14","modified_gmt":"2026-05-02T23:45:14","slug":"lady-di-esta-de-regreso-preparan-un-nuevo-documental-con-videos-ineditos","status":"publish","type":"post","link":"https:\/\/radioclanfm.com\/clanespectaculos\/lady-di-esta-de-regreso-preparan-un-nuevo-documental-con-videos-ineditos\/","title":{"rendered":"Lady Di est\u00e1 de regreso: preparan un nuevo documental con videos in\u00e9ditos"},"content":{"rendered":"<p>Diana: la verdad silenciada promete mostrar los pensamientos sinceros que la princesa tuvo sobre Carlos y Camila.<\/p>\n<p class=\"paragraph font__body-regular\">Una serie documental presentar\u00e1 por primera vez grabaciones in\u00e9ditas de la princesa Diana de Gales (1961-1997) que permanecieron ocultos durante d\u00e9cadas y que explorar\u00e1 \u201cla vida jam\u00e1s contada\u201d de la<b>\u00a0carism\u00e1tica arist\u00f3crata de la familia real brit\u00e1nica.<\/b><\/p>\n<div id=\"ad-slot-infeed\" class=\"infeed-container ad-slot-infeed ad-slot\" data-adtype=\"infeed\" data-lazyload=\"1\" data-google-query-id=\"CP-e2cHkm5QDFY41uQYd5EYr1g\">\n<div id=\"google_ads_iframe_\/113951150\/tn-arc\/nota\/infeed_0__container__\"><iframe id=\"google_ads_iframe_\/113951150\/tn-arc\/nota\/infeed_0\" tabindex=\"0\" title=\"Contenido de anuncios de terceros\" name=\"google_ads_iframe_\/113951150\/tn-arc\/nota\/infeed_0\" width=\"1\" height=\"1\" frameborder=\"0\" marginwidth=\"0\" marginheight=\"0\" scrolling=\"no\" aria-label=\"Anuncio\" data-google-container-id=\"9\" data-load-complete=\"true\" data-mce-fragment=\"1\"><\/iframe><\/div>\n<\/div>\n<p class=\"paragraph font__body-regular\">La productora brit\u00e1nica Love Monday, junto al bi\u00f3grafo Andrew Morton y su confidente James Colthurst, ha obtenido acceso exclusivo a\u00a0<b>cinco horas de conversaciones grabadas en 1991<\/b>\u00a0que desaf\u00edan la imagen tradicional de Diana como v\u00edctima para revelar una narrativa mucho m\u00e1s compleja sobre su identidad, seg\u00fan inform\u00f3 la agencia Deadline.<\/p>\n<div id=\"standard_1\" class=\"st-placement standard_1 inArticle\">\n<div class=\"st-adunit-inarticle st-inarticle-slot\">\n<div class=\"st-adunit st-adunit-tagged st-reset st-show\"><\/div>\n<\/div>\n<\/div>\n<div data-mrf-experience=\"IL_RNrGCM52Q_ui4aMax3fibg\"><\/div>\n<figure class=\"\" data-testid=\"figure-testid\">\n<div class=\"aspect_ratio__container\"><picture class=\"responsive-image\"><source srcset=\"https:\/\/tn.com.ar\/resizer\/v2\/lady-di-el-rey-carlos-y-camila-parker-un-triangulo-amoroso-que-tuvo-la-atencion-de-la-prensa-britanica-fotos-ap-E2VU6F4EJJF5TLLSNVUFGO2J2U.jpg?auth=c49f9a747eacf3a957977ec833c1d5cd3895ca94bb263c1adf1d72de3ba828a1&amp;width=767\" type=\"image\/jpg\" media=\"(max-width: 728px)\" \/><source srcset=\"https:\/\/tn.com.ar\/resizer\/v2\/lady-di-el-rey-carlos-y-camila-parker-un-triangulo-amoroso-que-tuvo-la-atencion-de-la-prensa-britanica-fotos-ap-E2VU6F4EJJF5TLLSNVUFGO2J2U.jpg?auth=c49f9a747eacf3a957977ec833c1d5cd3895ca94bb263c1adf1d72de3ba828a1&amp;width=1023\" type=\"image\/jpg\" media=\"(max-width: 1023px)\" \/><source srcset=\"https:\/\/tn.com.ar\/resizer\/v2\/lady-di-el-rey-carlos-y-camila-parker-un-triangulo-amoroso-que-tuvo-la-atencion-de-la-prensa-britanica-fotos-ap-E2VU6F4EJJF5TLLSNVUFGO2J2U.jpg?auth=c49f9a747eacf3a957977ec833c1d5cd3895ca94bb263c1adf1d72de3ba828a1&amp;width=1440\" type=\"image\/jpg\" \/><img loading=\"lazy\" decoding=\"async\" class=\"image content-image image_placeholder\" src=\"https:\/\/tn.com.ar\/resizer\/v2\/lady-di-el-rey-carlos-y-camila-parker-un-triangulo-amoroso-que-tuvo-la-atencion-de-la-prensa-britanica-fotos-ap-E2VU6F4EJJF5TLLSNVUFGO2J2U.jpg?auth=c49f9a747eacf3a957977ec833c1d5cd3895ca94bb263c1adf1d72de3ba828a1&amp;width=767\" alt=\"Lady Di, el Rey Carlos y Camila Parker, un tri\u00e1ngulo amoroso que tuvo la atenci\u00f3n de la prensa brit\u00e1nica. (Fotos: AP)\" width=\"767\" height=\"430\" data-testid=\"loading-testid\" \/><\/picture><\/div><figcaption class=\"caption_image\" data-testid=\"figcaption-testid\">\n<div class=\"image_caption \">Lady Di, el Rey Carlos y Camila Parker, un tri\u00e1ngulo amoroso que tuvo la atenci\u00f3n de la prensa brit\u00e1nica. (Fotos: AP)<\/div>\n<\/figcaption><\/figure>\n<p class=\"paragraph font__body-regular\">Esta serie documental, todav\u00eda sin fecha de estreno, constar\u00e1 de tres partes y tendr\u00e1 por t\u00edtulo Diana: The Unheard Truth \u2018Diana: la verdad silenciada).<\/p>\n<p class=\"paragraph font__body-regular\">Las grabaciones revelar\u00e1n\u00a0<b>los pensamientos de Diana sobre su exmarido Carlos<\/b>, ahora rey Carlos III, su actual esposa Camila e incluso Andr\u00e9s Mountbatten-Windsor, quien entonces era el pr\u00edncipe Andr\u00e9s.<\/p>\n<p class=\"paragraph font__body-regular\">Tambi\u00e9n prev\u00e9 incluir testimonios de las personas m\u00e1s cercanas a Diana, como una compa\u00f1era de colegio que nunca antes hab\u00eda hablado ante las c\u00e1maras o el\u00a0<b>peluquero que la acompa\u00f1\u00f3 durante toda la d\u00e9cada de los noventa.<\/b><\/p>\n<figure class=\"\" data-testid=\"figure-testid\">\n<div class=\"aspect_ratio__container\"><picture class=\"responsive-image\"><source srcset=\"https:\/\/tn.com.ar\/resizer\/v2\/el-recordado-vestido-de-la-venganza-de-lady-di-la-mayor-afronta-contra-carlos-y-la-corona-despues-de-su-escandaloso-divorcio-foto-instagram-MTACV4U27VFIJOTNVK3HRXMSVY.png?auth=d5034170745b36410d7da5e2982a0c2677e96ec00a57e6509b2e6ebbceee50f0&amp;width=767\" type=\"image\/jpg\" media=\"(max-width: 728px)\" \/><source srcset=\"https:\/\/tn.com.ar\/resizer\/v2\/el-recordado-vestido-de-la-venganza-de-lady-di-la-mayor-afronta-contra-carlos-y-la-corona-despues-de-su-escandaloso-divorcio-foto-instagram-MTACV4U27VFIJOTNVK3HRXMSVY.png?auth=d5034170745b36410d7da5e2982a0c2677e96ec00a57e6509b2e6ebbceee50f0&amp;width=1023\" type=\"image\/jpg\" media=\"(max-width: 1023px)\" \/><source srcset=\"https:\/\/tn.com.ar\/resizer\/v2\/el-recordado-vestido-de-la-venganza-de-lady-di-la-mayor-afronta-contra-carlos-y-la-corona-despues-de-su-escandaloso-divorcio-foto-instagram-MTACV4U27VFIJOTNVK3HRXMSVY.png?auth=d5034170745b36410d7da5e2982a0c2677e96ec00a57e6509b2e6ebbceee50f0&amp;width=1440\" type=\"image\/jpg\" \/><img loading=\"lazy\" decoding=\"async\" class=\"image content-image image_placeholder\" src=\"https:\/\/tn.com.ar\/resizer\/v2\/el-recordado-vestido-de-la-venganza-de-lady-di-la-mayor-afronta-contra-carlos-y-la-corona-despues-de-su-escandaloso-divorcio-foto-instagram-MTACV4U27VFIJOTNVK3HRXMSVY.png?auth=d5034170745b36410d7da5e2982a0c2677e96ec00a57e6509b2e6ebbceee50f0&amp;width=767\" alt=\"El recordado &quot;vestido de la venganza&quot; de Lady Di, la mayor afronta contra Carlos y la Corona, despu\u00e9s de su escandaloso divorcio. (Foto: Instagram)\" width=\"767\" height=\"959\" data-testid=\"loading-testid\" \/><\/picture><\/div><figcaption class=\"caption_image\" data-testid=\"figcaption-testid\">\n<div class=\"image_caption \">El recordado &#8220;vestido de la venganza&#8221; de Lady Di, la mayor afronta contra Carlos y la Corona, despu\u00e9s de su escandaloso divorcio. (Foto: Instagram)<\/div>\n<\/figcaption><\/figure>\n<p class=\"paragraph font__body-regular\">Considerada una de las integrantes m\u00e1s queridas y carism\u00e1ticas de la familia real brit\u00e1nica,\u00a0<b>Diana de Gales<\/b>\u00a0se consolid\u00f3 adem\u00e1s como una<b>\u00a0influyente pionera de la moda\u00a0<\/b>cuyo estilo sigue inspirando a nivel global.<\/p>\n<p class=\"paragraph font__body-regular\">Su tr\u00e1gico fallecimiento en un accidente automovil\u00edstico en 1997 en Par\u00eds caus\u00f3 un<b>\u00a0gran impacto global<\/b>\u00a0y dej\u00f3 un legado que todav\u00eda perdura en la sociedad actual.<\/p>\n<figure class=\"\" data-testid=\"figure-testid\">\n<div class=\"aspect_ratio__container\"><picture class=\"responsive-image\"><source srcset=\"https:\/\/tn.com.ar\/resizer\/v2\/kristen-stewart-otra-vez-irreconocible-como-lady-di-durante-el-rodaje-de-spencer-N6NNH4ZG2BF4RG4A4OCW4GMIRQ.jpg?auth=f7d84227b6ec8914b164cad1504db94893c8ec61ab7dfebd9463e239e66f3117&amp;width=767\" type=\"image\/jpg\" media=\"(max-width: 728px)\" \/><source srcset=\"https:\/\/tn.com.ar\/resizer\/v2\/kristen-stewart-otra-vez-irreconocible-como-lady-di-durante-el-rodaje-de-spencer-N6NNH4ZG2BF4RG4A4OCW4GMIRQ.jpg?auth=f7d84227b6ec8914b164cad1504db94893c8ec61ab7dfebd9463e239e66f3117&amp;width=1023\" type=\"image\/jpg\" media=\"(max-width: 1023px)\" \/><source srcset=\"https:\/\/tn.com.ar\/resizer\/v2\/kristen-stewart-otra-vez-irreconocible-como-lady-di-durante-el-rodaje-de-spencer-N6NNH4ZG2BF4RG4A4OCW4GMIRQ.jpg?auth=f7d84227b6ec8914b164cad1504db94893c8ec61ab7dfebd9463e239e66f3117&amp;width=1440\" type=\"image\/jpg\" \/><img loading=\"lazy\" decoding=\"async\" class=\"image content-image image_placeholder\" src=\"https:\/\/tn.com.ar\/resizer\/v2\/kristen-stewart-otra-vez-irreconocible-como-lady-di-durante-el-rodaje-de-spencer-N6NNH4ZG2BF4RG4A4OCW4GMIRQ.jpg?auth=f7d84227b6ec8914b164cad1504db94893c8ec61ab7dfebd9463e239e66f3117&amp;width=767\" alt=\"Kristen Stewart, otra vez irreconocible como Lady Di durante el rodaje de Spencer\" width=\"767\" height=\"431\" data-testid=\"loading-testid\" \/><\/picture><\/div><figcaption class=\"caption_image\" data-testid=\"figcaption-testid\">\n<div class=\"image_caption \">Kristen Stewart, otra vez irreconocible como Lady Di durante el rodaje de Spencer<\/div>\n<\/figcaption><\/figure>\n<p class=\"paragraph font__body-regular\">Su vida ha inspirado numerosas producciones en el cine y la televisi\u00f3n a lo largo de los a\u00f1os, como la pel\u00edcula \u2018Spencer\u2019, protagonizada por\u00a0<b>Kristen Stewart<\/b>, o la exitosa serie de Netflix, \u2018The Crown\u2019, que narra su compleja relaci\u00f3n con la familia real brit\u00e1nica.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Diana: la verdad silenciada promete mostrar los pensamientos sinceros que la princesa tuvo sobre Carlos y Camila. Una serie documental presentar\u00e1 por primera vez grabaciones in\u00e9ditas de la princesa Diana de Gales (1961-1997) que permanecieron ocultos durante d\u00e9cadas y que explorar\u00e1 \u201cla vida jam\u00e1s contada\u201d de la\u00a0carism\u00e1tica arist\u00f3crata de la familia real brit\u00e1nica. La productora [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":16054,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"rop_custom_images_group":[],"rop_custom_messages_group":[],"rop_publish_now":"initial","rop_publish_now_accounts":[],"rop_publish_now_history":[],"rop_publish_now_status":"pending","footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","enabled":false},"version":2}},"categories":[13],"tags":[],"class_list":{"0":"post-16053","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-hollywood"},"jetpack_publicize_connections":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Lady Di est\u00e1 de regreso: preparan un nuevo documental con videos in\u00e9ditos - CLAN ESPECTACULOS<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/radioclanfm.com\/clanespectaculos\/lady-di-esta-de-regreso-preparan-un-nuevo-documental-con-videos-ineditos\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Lady Di est\u00e1 de regreso: preparan un nuevo documental con videos in\u00e9ditos - CLAN ESPECTACULOS\" \/>\n<meta property=\"og:description\" content=\"Diana: la verdad silenciada promete mostrar los pensamientos sinceros que la princesa tuvo sobre Carlos y Camila. Una serie documental presentar\u00e1 por primera vez grabaciones in\u00e9ditas de la princesa Diana de Gales (1961-1997) que permanecieron ocultos durante d\u00e9cadas y que explorar\u00e1 \u201cla vida jam\u00e1s contada\u201d de la\u00a0carism\u00e1tica arist\u00f3crata de la familia real brit\u00e1nica. La productora [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/radioclanfm.com\/clanespectaculos\/lady-di-esta-de-regreso-preparan-un-nuevo-documental-con-videos-ineditos\/\" \/>\n<meta property=\"og:site_name\" content=\"CLAN ESPECTACULOS\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/clanespectaculos\/\" \/>\n<meta property=\"article:published_time\" content=\"2026-05-02T23:45:14+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/radioclanfm.com\/clanespectaculos\/wp-content\/uploads\/sites\/2\/2026\/05\/cEDbgArs.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"900\" \/>\n\t<meta property=\"og:image:height\" content=\"504\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"E-GRUPOCLAN\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@clanespectok\" \/>\n<meta name=\"twitter:site\" content=\"@clanespectok\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"E-GRUPOCLAN\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/radioclanfm.com\\\/clanespectaculos\\\/lady-di-esta-de-regreso-preparan-un-nuevo-documental-con-videos-ineditos\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/radioclanfm.com\\\/clanespectaculos\\\/lady-di-esta-de-regreso-preparan-un-nuevo-documental-con-videos-ineditos\\\/\"},\"author\":{\"name\":\"E-GRUPOCLAN\",\"@id\":\"https:\\\/\\\/radioclanfm.com\\\/clanespectaculos\\\/#\\\/schema\\\/person\\\/9734813083303230f3ad84d99171b20c\"},\"headline\":\"Lady Di est\u00e1 de regreso: preparan un nuevo documental con videos in\u00e9ditos\",\"datePublished\":\"2026-05-02T23:45:14+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/radioclanfm.com\\\/clanespectaculos\\\/lady-di-esta-de-regreso-preparan-un-nuevo-documental-con-videos-ineditos\\\/\"},\"wordCount\":410,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/radioclanfm.com\\\/clanespectaculos\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/radioclanfm.com\\\/clanespectaculos\\\/lady-di-esta-de-regreso-preparan-un-nuevo-documental-con-videos-ineditos\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/radioclanfm.com\\\/clanespectaculos\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2026\\\/05\\\/cEDbgArs.jpg\",\"articleSection\":[\"Hollywood\"],\"inLanguage\":\"es-AR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/radioclanfm.com\\\/clanespectaculos\\\/lady-di-esta-de-regreso-preparan-un-nuevo-documental-con-videos-ineditos\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/radioclanfm.com\\\/clanespectaculos\\\/lady-di-esta-de-regreso-preparan-un-nuevo-documental-con-videos-ineditos\\\/\",\"url\":\"https:\\\/\\\/radioclanfm.com\\\/clanespectaculos\\\/lady-di-esta-de-regreso-preparan-un-nuevo-documental-con-videos-ineditos\\\/\",\"name\":\"Lady Di est\u00e1 de regreso: preparan un nuevo documental con videos in\u00e9ditos - CLAN ESPECTACULOS\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/radioclanfm.com\\\/clanespectaculos\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/radioclanfm.com\\\/clanespectaculos\\\/lady-di-esta-de-regreso-preparan-un-nuevo-documental-con-videos-ineditos\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/radioclanfm.com\\\/clanespectaculos\\\/lady-di-esta-de-regreso-preparan-un-nuevo-documental-con-videos-ineditos\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/radioclanfm.com\\\/clanespectaculos\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2026\\\/05\\\/cEDbgArs.jpg\",\"datePublished\":\"2026-05-02T23:45:14+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/radioclanfm.com\\\/clanespectaculos\\\/lady-di-esta-de-regreso-preparan-un-nuevo-documental-con-videos-ineditos\\\/#breadcrumb\"},\"inLanguage\":\"es-AR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/radioclanfm.com\\\/clanespectaculos\\\/lady-di-esta-de-regreso-preparan-un-nuevo-documental-con-videos-ineditos\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es-AR\",\"@id\":\"https:\\\/\\\/radioclanfm.com\\\/clanespectaculos\\\/lady-di-esta-de-regreso-preparan-un-nuevo-documental-con-videos-ineditos\\\/#primaryimage\",\"url\":\"https:\\\/\\\/radioclanfm.com\\\/clanespectaculos\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2026\\\/05\\\/cEDbgArs.jpg\",\"contentUrl\":\"https:\\\/\\\/radioclanfm.com\\\/clanespectaculos\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2026\\\/05\\\/cEDbgArs.jpg\",\"width\":900,\"height\":504},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/radioclanfm.com\\\/clanespectaculos\\\/lady-di-esta-de-regreso-preparan-un-nuevo-documental-con-videos-ineditos\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inicio\",\"item\":\"https:\\\/\\\/radioclanfm.com\\\/clanespectaculos\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Lady Di est\u00e1 de regreso: preparan un nuevo documental con videos in\u00e9ditos\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/radioclanfm.com\\\/clanespectaculos\\\/#website\",\"url\":\"https:\\\/\\\/radioclanfm.com\\\/clanespectaculos\\\/\",\"name\":\"CLAN ESPECTACULOS\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/radioclanfm.com\\\/clanespectaculos\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/radioclanfm.com\\\/clanespectaculos\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es-AR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/radioclanfm.com\\\/clanespectaculos\\\/#organization\",\"name\":\"CLAN ESPECTACULOS\",\"url\":\"https:\\\/\\\/radioclanfm.com\\\/clanespectaculos\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es-AR\",\"@id\":\"https:\\\/\\\/radioclanfm.com\\\/clanespectaculos\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/radioclanfm.com\\\/clanespectaculos\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2026\\\/04\\\/ChatGPT-Image-23-mar-2026-10_09_00.png\",\"contentUrl\":\"https:\\\/\\\/radioclanfm.com\\\/clanespectaculos\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2026\\\/04\\\/ChatGPT-Image-23-mar-2026-10_09_00.png\",\"width\":1024,\"height\":1024,\"caption\":\"CLAN ESPECTACULOS\"},\"image\":{\"@id\":\"https:\\\/\\\/radioclanfm.com\\\/clanespectaculos\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/clanespectaculos\\\/\",\"https:\\\/\\\/x.com\\\/clanespectok\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/radioclanfm.com\\\/clanespectaculos\\\/#\\\/schema\\\/person\\\/9734813083303230f3ad84d99171b20c\",\"name\":\"E-GRUPOCLAN\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es-AR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/af6e19837c3d6a212034a48c7b3818d2ac1826f6025df0155da5a186ad321d79?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/af6e19837c3d6a212034a48c7b3818d2ac1826f6025df0155da5a186ad321d79?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/af6e19837c3d6a212034a48c7b3818d2ac1826f6025df0155da5a186ad321d79?s=96&d=mm&r=g\",\"caption\":\"E-GRUPOCLAN\"},\"sameAs\":[\"https:\\\/\\\/radioclanfm.com\"],\"url\":\"https:\\\/\\\/radioclanfm.com\\\/clanespectaculos\\\/author\\\/admin\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Lady Di est\u00e1 de regreso: preparan un nuevo documental con videos in\u00e9ditos - CLAN ESPECTACULOS","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/radioclanfm.com\/clanespectaculos\/lady-di-esta-de-regreso-preparan-un-nuevo-documental-con-videos-ineditos\/","og_locale":"es_ES","og_type":"article","og_title":"Lady Di est\u00e1 de regreso: preparan un nuevo documental con videos in\u00e9ditos - CLAN ESPECTACULOS","og_description":"Diana: la verdad silenciada promete mostrar los pensamientos sinceros que la princesa tuvo sobre Carlos y Camila. Una serie documental presentar\u00e1 por primera vez grabaciones in\u00e9ditas de la princesa Diana de Gales (1961-1997) que permanecieron ocultos durante d\u00e9cadas y que explorar\u00e1 \u201cla vida jam\u00e1s contada\u201d de la\u00a0carism\u00e1tica arist\u00f3crata de la familia real brit\u00e1nica. La productora [&hellip;]","og_url":"https:\/\/radioclanfm.com\/clanespectaculos\/lady-di-esta-de-regreso-preparan-un-nuevo-documental-con-videos-ineditos\/","og_site_name":"CLAN ESPECTACULOS","article_publisher":"https:\/\/www.facebook.com\/clanespectaculos\/","article_published_time":"2026-05-02T23:45:14+00:00","og_image":[{"width":900,"height":504,"url":"https:\/\/radioclanfm.com\/clanespectaculos\/wp-content\/uploads\/sites\/2\/2026\/05\/cEDbgArs.jpg","type":"image\/jpeg"}],"author":"E-GRUPOCLAN","twitter_card":"summary_large_image","twitter_creator":"@clanespectok","twitter_site":"@clanespectok","twitter_misc":{"Escrito por":"E-GRUPOCLAN","Tiempo de lectura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/radioclanfm.com\/clanespectaculos\/lady-di-esta-de-regreso-preparan-un-nuevo-documental-con-videos-ineditos\/#article","isPartOf":{"@id":"https:\/\/radioclanfm.com\/clanespectaculos\/lady-di-esta-de-regreso-preparan-un-nuevo-documental-con-videos-ineditos\/"},"author":{"name":"E-GRUPOCLAN","@id":"https:\/\/radioclanfm.com\/clanespectaculos\/#\/schema\/person\/9734813083303230f3ad84d99171b20c"},"headline":"Lady Di est\u00e1 de regreso: preparan un nuevo documental con videos in\u00e9ditos","datePublished":"2026-05-02T23:45:14+00:00","mainEntityOfPage":{"@id":"https:\/\/radioclanfm.com\/clanespectaculos\/lady-di-esta-de-regreso-preparan-un-nuevo-documental-con-videos-ineditos\/"},"wordCount":410,"commentCount":0,"publisher":{"@id":"https:\/\/radioclanfm.com\/clanespectaculos\/#organization"},"image":{"@id":"https:\/\/radioclanfm.com\/clanespectaculos\/lady-di-esta-de-regreso-preparan-un-nuevo-documental-con-videos-ineditos\/#primaryimage"},"thumbnailUrl":"https:\/\/radioclanfm.com\/clanespectaculos\/wp-content\/uploads\/sites\/2\/2026\/05\/cEDbgArs.jpg","articleSection":["Hollywood"],"inLanguage":"es-AR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/radioclanfm.com\/clanespectaculos\/lady-di-esta-de-regreso-preparan-un-nuevo-documental-con-videos-ineditos\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/radioclanfm.com\/clanespectaculos\/lady-di-esta-de-regreso-preparan-un-nuevo-documental-con-videos-ineditos\/","url":"https:\/\/radioclanfm.com\/clanespectaculos\/lady-di-esta-de-regreso-preparan-un-nuevo-documental-con-videos-ineditos\/","name":"Lady Di est\u00e1 de regreso: preparan un nuevo documental con videos in\u00e9ditos - CLAN ESPECTACULOS","isPartOf":{"@id":"https:\/\/radioclanfm.com\/clanespectaculos\/#website"},"primaryImageOfPage":{"@id":"https:\/\/radioclanfm.com\/clanespectaculos\/lady-di-esta-de-regreso-preparan-un-nuevo-documental-con-videos-ineditos\/#primaryimage"},"image":{"@id":"https:\/\/radioclanfm.com\/clanespectaculos\/lady-di-esta-de-regreso-preparan-un-nuevo-documental-con-videos-ineditos\/#primaryimage"},"thumbnailUrl":"https:\/\/radioclanfm.com\/clanespectaculos\/wp-content\/uploads\/sites\/2\/2026\/05\/cEDbgArs.jpg","datePublished":"2026-05-02T23:45:14+00:00","breadcrumb":{"@id":"https:\/\/radioclanfm.com\/clanespectaculos\/lady-di-esta-de-regreso-preparan-un-nuevo-documental-con-videos-ineditos\/#breadcrumb"},"inLanguage":"es-AR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/radioclanfm.com\/clanespectaculos\/lady-di-esta-de-regreso-preparan-un-nuevo-documental-con-videos-ineditos\/"]}]},{"@type":"ImageObject","inLanguage":"es-AR","@id":"https:\/\/radioclanfm.com\/clanespectaculos\/lady-di-esta-de-regreso-preparan-un-nuevo-documental-con-videos-ineditos\/#primaryimage","url":"https:\/\/radioclanfm.com\/clanespectaculos\/wp-content\/uploads\/sites\/2\/2026\/05\/cEDbgArs.jpg","contentUrl":"https:\/\/radioclanfm.com\/clanespectaculos\/wp-content\/uploads\/sites\/2\/2026\/05\/cEDbgArs.jpg","width":900,"height":504},{"@type":"BreadcrumbList","@id":"https:\/\/radioclanfm.com\/clanespectaculos\/lady-di-esta-de-regreso-preparan-un-nuevo-documental-con-videos-ineditos\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inicio","item":"https:\/\/radioclanfm.com\/clanespectaculos\/"},{"@type":"ListItem","position":2,"name":"Lady Di est\u00e1 de regreso: preparan un nuevo documental con videos in\u00e9ditos"}]},{"@type":"WebSite","@id":"https:\/\/radioclanfm.com\/clanespectaculos\/#website","url":"https:\/\/radioclanfm.com\/clanespectaculos\/","name":"CLAN ESPECTACULOS","description":"","publisher":{"@id":"https:\/\/radioclanfm.com\/clanespectaculos\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/radioclanfm.com\/clanespectaculos\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es-AR"},{"@type":"Organization","@id":"https:\/\/radioclanfm.com\/clanespectaculos\/#organization","name":"CLAN ESPECTACULOS","url":"https:\/\/radioclanfm.com\/clanespectaculos\/","logo":{"@type":"ImageObject","inLanguage":"es-AR","@id":"https:\/\/radioclanfm.com\/clanespectaculos\/#\/schema\/logo\/image\/","url":"https:\/\/radioclanfm.com\/clanespectaculos\/wp-content\/uploads\/sites\/2\/2026\/04\/ChatGPT-Image-23-mar-2026-10_09_00.png","contentUrl":"https:\/\/radioclanfm.com\/clanespectaculos\/wp-content\/uploads\/sites\/2\/2026\/04\/ChatGPT-Image-23-mar-2026-10_09_00.png","width":1024,"height":1024,"caption":"CLAN ESPECTACULOS"},"image":{"@id":"https:\/\/radioclanfm.com\/clanespectaculos\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/clanespectaculos\/","https:\/\/x.com\/clanespectok"]},{"@type":"Person","@id":"https:\/\/radioclanfm.com\/clanespectaculos\/#\/schema\/person\/9734813083303230f3ad84d99171b20c","name":"E-GRUPOCLAN","image":{"@type":"ImageObject","inLanguage":"es-AR","@id":"https:\/\/secure.gravatar.com\/avatar\/af6e19837c3d6a212034a48c7b3818d2ac1826f6025df0155da5a186ad321d79?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/af6e19837c3d6a212034a48c7b3818d2ac1826f6025df0155da5a186ad321d79?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/af6e19837c3d6a212034a48c7b3818d2ac1826f6025df0155da5a186ad321d79?s=96&d=mm&r=g","caption":"E-GRUPOCLAN"},"sameAs":["https:\/\/radioclanfm.com"],"url":"https:\/\/radioclanfm.com\/clanespectaculos\/author\/admin\/"}]}},"_links":{"self":[{"href":"https:\/\/radioclanfm.com\/clanespectaculos\/wp-json\/wp\/v2\/posts\/16053","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/radioclanfm.com\/clanespectaculos\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/radioclanfm.com\/clanespectaculos\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/radioclanfm.com\/clanespectaculos\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/radioclanfm.com\/clanespectaculos\/wp-json\/wp\/v2\/comments?post=16053"}],"version-history":[{"count":1,"href":"https:\/\/radioclanfm.com\/clanespectaculos\/wp-json\/wp\/v2\/posts\/16053\/revisions"}],"predecessor-version":[{"id":16055,"href":"https:\/\/radioclanfm.com\/clanespectaculos\/wp-json\/wp\/v2\/posts\/16053\/revisions\/16055"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/radioclanfm.com\/clanespectaculos\/wp-json\/wp\/v2\/media\/16054"}],"wp:attachment":[{"href":"https:\/\/radioclanfm.com\/clanespectaculos\/wp-json\/wp\/v2\/media?parent=16053"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/radioclanfm.com\/clanespectaculos\/wp-json\/wp\/v2\/categories?post=16053"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/radioclanfm.com\/clanespectaculos\/wp-json\/wp\/v2\/tags?post=16053"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}